{"id":17936,"date":"2016-08-25T10:45:23","date_gmt":"2016-08-25T08:45:23","guid":{"rendered":"http:\/\/gastronomicament.cat\/?p=17936"},"modified":"2022-04-07T11:06:10","modified_gmt":"2022-04-07T09:06:10","slug":"manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","title":{"rendered":"Manuel Ruiz, Manu Catman, nou ambaixador de l&#8217;Oli de Mallorca"},"content":{"rendered":"<p>El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com <a href=\"www.cocinandoconcatman.com\/\" title=\"Cocinando con Catman\" target=\"_blank\" rel=\"noopener\">Manu Catman<\/a>&#8211; Ambaixador de l\u2019Oli de Mallorca 2016-2017.<\/p>\n<p>El president de la DO Oli de Mallorca, Sebasti\u00e0 Solivellas ha fet entrega del diploma que l\u2019acredita com ambaixador despr\u00e9s de destacar la seva tasca en la difusi\u00f3 de l\u2019Oli de Mallorca, aix\u00ed com de l\u2019oli d\u2019oliva verge extra a trav\u00e9s del seu bloc Cocinando con Catman, un dels m\u00e9s influents de la blogosfera gastron\u00f2mica en castell\u00e0.<\/p>\n<p>Una tasca encara necess\u00e0ria ja que, com assenyal\u00e0 Solivellas, l\u2019oli d\u2019oliva verge extra \u00e9s encara desconegut per molts consumidors, que no coneixen molt b\u00e9 la difer\u00e8ncia entre un oli verge extra, un oli verge i un oli com\u00fa, refinat.<\/p>\n<p>Manuel Ruiz, va agrair el seu nomenament i va afirmar el seu comprom\u00eds \u201camb el producte i la gastronomia de les Balears, els quals s\u2019haurien de promoure com un atractiu tur\u00edstic m\u00e9s, anant m\u00e9s enll\u00e0 de l\u2019ensa\u00efmada i la sobrassada, tals com l\u2019oli de Mallorca\u201d, afegint que \u201coli d\u2019oliva verge extra \u00e9s el millor amic de la cuina\u201d.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman&#8211; Ambaixador de l\u2019Oli de Mallorca 2016-2017. El president de la DO Oli de Mallorca, Sebasti\u00e0 Solivellas ha fet entrega del diploma que l\u2019acredita com ambaixador despr\u00e9s de destacar la seva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17937,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[692],"tags":[],"coauthors":[],"class_list":["post-17936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manuel Ruiz, Manu Catman, nou ambaixador de l&#039;Oli de Mallorca - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Manuel Ruiz, Manu Catman, nou ambaixador de l&#039;Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuel Ruiz, Manu Catman, nou ambaixador de l&#039;Oli de Mallorca - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Manuel Ruiz, Manu Catman, nou ambaixador de l&#039;Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-25T08:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T09:06:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Manuel Ruiz, Manu Catman, nou ambaixador de l&#8217;Oli de Mallorca\",\"datePublished\":\"2016-08-25T08:45:23+00:00\",\"dateModified\":\"2022-04-07T09:06:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/ambaixador-oli-de-mallorca-2016-2017.jpg\",\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\",\"name\":\"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/ambaixador-oli-de-mallorca-2016-2017.jpg\",\"datePublished\":\"2016-08-25T08:45:23+00:00\",\"dateModified\":\"2022-04-07T09:06:10+00:00\",\"description\":\"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli\",\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/ambaixador-oli-de-mallorca-2016-2017.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/ambaixador-oli-de-mallorca-2016-2017.jpg\",\"width\":1024,\"height\":682},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca - Gastron\u00f2micament","description":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","og_locale":"ca_ES","og_type":"article","og_title":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca - Gastron\u00f2micament","og_description":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli","og_url":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","og_site_name":"Gastron\u00f2micament","article_published_time":"2016-08-25T08:45:23+00:00","article_modified_time":"2022-04-07T09:06:10+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Manuel Ruiz, Manu Catman, nou ambaixador de l&#8217;Oli de Mallorca","datePublished":"2016-08-25T08:45:23+00:00","dateModified":"2022-04-07T09:06:10+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg","articleSection":["Actualitat"],"inLanguage":"ca-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","url":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca","name":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg","datePublished":"2016-08-25T08:45:23+00:00","dateModified":"2022-04-07T09:06:10+00:00","description":"Manuel Ruiz, Manu Catman, nou ambaixador de l'Oli de Mallorca Actualitat El Consell Regulador de la DO Oli de Mallorca ha nomenat al blogaire de cuina Manuel Ruiz -m\u00e9s conegut a les xarxes com Manu Catman- Ambaixador de l\u2019Oli","inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/manuel-ruiz-manu-catman-nou-ambaixador-de-loli-de-mallorca#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/08\/ambaixador-oli-de-mallorca-2016-2017.jpg","width":1024,"height":682},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/ca\/#website","url":"https:\/\/gastronomicament.cat\/ca\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/ca\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/ca\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/17936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/comments?post=17936"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/17936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media\/17937"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media?parent=17936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/categories?post=17936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/tags?post=17936"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/coauthors?post=17936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}