{"id":18522,"date":"2016-11-22T16:19:25","date_gmt":"2016-11-22T15:19:25","guid":{"rendered":"http:\/\/gastronomicament.cat\/?p=18522"},"modified":"2022-04-07T11:06:45","modified_gmt":"2022-04-07T09:06:45","slug":"tapes-ball-la-fira-de-santa-catalina-bunyola-2016","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016","title":{"rendered":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016"},"content":{"rendered":"<p>Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.<\/p>\n<p>D&#8217;entre les activitats previstes per l&#8217;Ajuntament de Bunyola, cal destacar els foguerons de dijous, el teatre de divendres i el ball i les tapes de dissabte, a m\u00e9s de l&#8217;oportunitat que s&#8217;oferir\u00e0 diumenge de viure la Fira.<\/p>\n<p><strong>Sens dubte una bona oportunitat per con\u00e8ixer sa Comuna i tot el poble de Bunyola amb aquesta Fira de Tramuntana.<\/strong><\/p>\n<p>Aqu\u00ed teniu el programa d&#8217;activitats:<\/p>\n<p><strong>Dijous 24<\/strong><\/p>\n<ul>\n<li>18.30 h: Presentaci\u00f3 del cartell fet pels alumnes de 6\u00e8 del CEIP Mestre Colom i del programa de la Fira de Santa Catalina<\/li>\n<li>19 h: Encesa de foguerons de Santa Catalina amb els xeremiers de Grallalsac pels carrers del poble.<\/li>\n<\/ul>\n<p><strong>Divendres 25<\/strong><\/p>\n<ul>\n<li>17.30 h: Commemoraci\u00f3 del Dia contra la Viol\u00e8ncia Masclista a la Pla\u00e7a, amb encesa d&#8217;espelmes i lectura de manifest.<\/li>\n<li>18 h: Presentaci\u00f3 del llibre <em>20 rutes en fam\u00edlia. Serra de Tramuntana<\/em>, de Joan Carles Palos, a la Casa de Cultura<\/li>\n<li>20.30 h: Show de Vivian Caoba a la Rectoria. Podeu recollir les entrades gratu\u00eftes a l&#8217;Ajuntament.<\/li>\n<\/ul>\n<p><strong>Dissabte 26\u00a0<\/strong><\/p>\n<ul>\n<li>10 h: Trobada de Xeremiers al pati del CEIP Mestre Colom<\/li>\n<li>11 h: Cercavila amb els Xeremiers pels carrers del poble<\/li>\n<li>12 h: Actuaci\u00f3 de colles de xeremiers a la Pla\u00e7a<\/li>\n<li>16 h: Sortida de Nordic Walking amb refugi de muntanya. Confirmau participaci\u00f3 al 971 716731<\/li>\n<li>17 hores: Trobada de ball en l\u00ednia<\/li>\n<li>19 h: Ball de bot. Ballada popular amb l&#8217;Escola de Ball de Bunyola<\/li>\n<li>20 h: Tapa i canya pels bars del poble<\/li>\n<li>21.30 h: Gramola, m\u00fasica de ball de sal\u00f3 i altres herbes.<\/li>\n<\/ul>\n<p><strong>Diumenge 27<\/strong><\/p>\n<ul>\n<li>9 h: Obertura de paradetes<\/li>\n<li>10 h: Plantada de gegants a la Pla\u00e7a<\/li>\n<li>11 h: Inauguraci\u00f3 de la Fira<\/li>\n<li>12.30 h: Cercavila batucada Rebombori<\/li>\n<li>19 h: Tancament de les paradetes<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter size-medium\" src=\"http:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Bunyola-Mallorca.jpg\" alt=\"\" width=\"533\" height=\"298\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":18529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[692],"tags":[],"coauthors":[],"class_list":["post-18522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-22T15:19:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T09:06:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016\",\"datePublished\":\"2016-11-22T15:19:25+00:00\",\"dateModified\":\"2022-04-07T09:06:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\"},\"wordCount\":310,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg\",\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\",\"name\":\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg\",\"datePublished\":\"2016-11-22T15:19:25+00:00\",\"dateModified\":\"2022-04-07T09:06:45+00:00\",\"description\":\"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.\",\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg\",\"width\":960,\"height\":450},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament","description":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016","og_locale":"ca_ES","og_type":"article","og_title":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament","og_description":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.","og_url":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016","og_site_name":"Gastron\u00f2micament","article_published_time":"2016-11-22T15:19:25+00:00","article_modified_time":"2022-04-07T09:06:45+00:00","og_image":[{"width":960,"height":450,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016","datePublished":"2016-11-22T15:19:25+00:00","dateModified":"2022-04-07T09:06:45+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016"},"wordCount":310,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg","articleSection":["Actualitat"],"inLanguage":"ca-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016","url":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016","name":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg","datePublished":"2016-11-22T15:19:25+00:00","dateModified":"2022-04-07T09:06:45+00:00","description":"Tapes i ball a la Fira de Santa Catalina a Bunyola 2016 Actualitat Aquest cap de setmana les tapes i el ball seran els protagonistes del programa de la Fira de Santa Catalina de Bunyola 2016. Els actes comencen dia dijous 24 i acaben diumenge 27, amb la Fira.","inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/tapes-ball-la-fira-de-santa-catalina-bunyola-2016#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/11\/Fira-de-Santa-Catalina-Bunyola-Mallorca-2016.jpg","width":960,"height":450},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/ca\/#website","url":"https:\/\/gastronomicament.cat\/ca\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/ca\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/ca\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/18522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/comments?post=18522"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/18522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media\/18529"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media?parent=18522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/categories?post=18522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/tags?post=18522"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/coauthors?post=18522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}