{"id":87335,"date":"2024-02-19T12:57:23","date_gmt":"2024-02-19T11:57:23","guid":{"rendered":"https:\/\/gastronomicament.cat\/?p=87335"},"modified":"2024-02-22T00:20:52","modified_gmt":"2024-02-21T23:20:52","slug":"manifestacio-dels-pagesos-a-mallorca","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca","title":{"rendered":"Manifestaci\u00f3 dels pagesos a Mallorca"},"content":{"rendered":"<p>Dia 19 de febrer, els pagesos de Mallorca es mobilitzaran en tractor des de diferents punts de l&#8217;illa cap a Palma. El motiu \u00e9s denunciar la situaci\u00f3 en qu\u00e8 es troba el sector.<\/p>\n<p>Les\u00a0<strong>demandes\u00a0<\/strong>en\u00a0<strong>l&#8217;\u00e0mbit\u00a0espanyol i europeu<\/strong>\u00a0s\u00f3n les seg\u00fcents:<\/p>\n<ul>\n<li>Hi ha\u00a0un exc\u00e9s de burocr\u00e0cia de les normatives de la UE, estatals i auton\u00f2miques<\/li>\n<li>Hi ha productes importats de tercers pa\u00efsos que no compleixin les normatives internes de la Uni\u00f3 Europea.<\/li>\n<li>Calen mesures urgents per fer front a la sequera i al canvi clim\u00e0tic.<\/li>\n<\/ul>\n<p>Les\u00a0<strong>demandes en l&#8217;\u00e0mbit\u00a0auton\u00f2mic<\/strong>\u00a0s\u00f3n:<\/p>\n<ul>\n<li>Disposar d&#8217;una administraci\u00f3 agr\u00e0ria al servei de la pagesia<\/li>\n<li>Promocionar el producte local<\/li>\n<li>Que hi hagi un desenvolupament legislatiu de la insularitat<\/li>\n<\/ul>\n<p>El\u00a0<strong>punt de trobada\u00a0<\/strong>dels tractors per a la<strong>\u00a0manifestaci\u00f3 del dia 19\u00a0<\/strong>ser\u00e0 l&#8217;Avinguda de M\u00e8xic, a partir de les 11 del mat\u00ed. Des d&#8217;all\u00e0, partiran cap a la Delegaci\u00f3 del Govern Espanyol i recorreran les Avingudes, Jaume III i el Passeig des Born.<\/p>\n<p>A banda d&#8217;aquestes demandes,\u00a0<strong>un grup de 50 pagesos professionals de 27 pobles<\/strong>, han exposat les dificultats amb qu\u00e8 topen dia s\u00ed dia tamb\u00e9 en un manifest\u00a0titulat &#8216;Per una Mallorca agroecol\u00f2gica i pagesa!&#8217; en qu\u00e8 expliquen els motius de la manifestaci\u00f3:<\/p>\n<ol>\n<li><strong> Perqu\u00e8 si no plou i no tenim ajuda ARA, potser ja no hi serem quan torni a ploure.<\/strong>Es fa insuportable veure com es tuda aigua als camps de golf, hotels, creuers, aeroports, jardins de gespa i piscines enormes mentre l&#8217;aigua depurada se&#8217;n va a la mar. Els pagesos, per\u00f2, serem els primers a patir restriccions tot i no representar ni el 10% del consum total. On s\u00f3n les depuradores, basses de reg i canalitzacions promeses fa d\u00e8cades?<\/li>\n<li><strong> Perqu\u00e8 els costos de producci\u00f3 s&#8217;han disparat i no podem traslladar-los als consumidors com si res.\u00a0<\/strong>Molta gent no pot comprar productes locals, no els coneix o no els troba. Aquests costos s\u00f3n assumits pels pagesos, una c\u00e0rrega que obliga a tancar l&#8217;explotaci\u00f3 o precaritzar-la m\u00e9s.<\/li>\n<li><strong> Perqu\u00e8 tot ve de fora. Estam perdent la poca sobirania aliment\u00e0ria que ens queda.<\/strong>Fa just vint anys prop del 50% del que menj\u00e0vem es feia aqu\u00ed i ara no arriba ni al 15%. Perdem explotacions, pagesos, aliments, coneixement, varietats, llengua i cultura. No podem ni volem caure m\u00e9s baix.<\/li>\n<li><strong> Perqu\u00e8 rebem 16 milions de turistes i la majoria se&#8217;n torna sense tastar cap producte local.\u00a0<\/strong>No \u00e9s acceptable que el 99% dels hotelers no tengui ni un producte mallorqu\u00ed als seus menjadors, que milers de bars i restaurants no ofereixin res local ni que molts supermercats, escoles i hospitals tenguin nom\u00e9s productes de fora.<\/li>\n<li><strong> Perqu\u00e8 a Mallorca ja hi ha m\u00e9s immobili\u00e0ries que pagesos.\u00a0<\/strong>Aquest model arrasa fora vila, ens roba l&#8217;aigua i la terra i omple el camp de ciment, estrangers rics i cans que ataquen a les nostres ovelles. I a damunt es queixen del renou dels picarols.<\/li>\n<li><strong> Perqu\u00e8 els nostres governants promouen la urbanitzaci\u00f3 massiva del camp,<\/strong>ens impedeix l&#8217;acc\u00e9s a terra i aigua i barra el pas als joves que serien el relleu que hem de menester. No podem comprar, ni llogar terra. Sense pagesos Mallorca no tendr\u00e0 aliments locals i sans.<\/li>\n<li><strong> Perqu\u00e8 si no plou i fa m\u00e9s calor no podem sembrar i els nostres animals no mengen.<\/strong>Cerquen i no troben i el preu del menjar animal s&#8217;ha disparat o no se&#8217;n troba. Mentre veim que el govern paga els llits nous i la promoci\u00f3 tur\u00edstica a grans cadenes hotelers que guanyen doblers a carretades.<\/li>\n<li><strong> Perqu\u00e8 importam aliments de l&#8217;altre cap de m\u00f3n amb un impacte ambiental enorme,\u00a0<\/strong>quan podem i sabem fer-los aqu\u00ed i de manera ecol\u00f2gica. Cal cr\u00e9ixer en pagesos i decr\u00e9ixer en ciment i places tur\u00edstiques.<\/li>\n<li><strong> Perqu\u00e8 els governs que tenim i hem tengut promouen la construcci\u00f3 massiva de pol\u00edgons fotovoltaics\u00a0<\/strong>dins la poca terra f\u00e8rtil que queda. Estan venuts a multinacionals energ\u00e8tiques i els regalen subvencions multimilion\u00e0ries dels impostos de tots. Sobren llocs degradats o urbans on posar aquestes plaques. De res servir\u00e0 aquesta energia si no tenim farina.<\/li>\n<li><strong> Perqu\u00e8 grans fons d&#8217;inversi\u00f3 estrangers compren les finques per urbanitzar<\/strong>, fer-hi hotels, pol\u00edgons solars, tafones i cellers que just cerquen edificar i especular. De tot manco produir aliments de qualitat per la poblaci\u00f3 local. I el camp est\u00e0 per aix\u00f2.<\/li>\n<li><strong> Perqu\u00e8 les ajudes promeses pels Governs arriben tard o no arriben.\u00a0<\/strong>Alguns pagesos no han cobrat encara ajudes concedides l&#8217;any 2019. No \u00e9s possible que l&#8217;administraci\u00f3 sigui tan mal pagadora nom\u00e9s amb el sector agrari.<\/li>\n<li><strong> Perqu\u00e8 les multinacionals ho monopolitzen tot afavorides pels tractats internacionals de &#8220;lliure comer\u00e7&#8221;<\/strong>. Imposen els preus que volen a tothom portant productes barats de llocs on s&#8217;explota encara m\u00e9s que aqu\u00ed a pagesos i ecosistemes.<\/li>\n<li><strong> Perqu\u00e8 les administracions remen a favor de l&#8217;agroind\u00fastria <\/strong>mentre ens tapen de tr\u00e0mits, paperassa i taxes rid\u00edcules als que ja ho feim b\u00e9, mentre les empreses grosses que apliquen herbicides i t\u00f2xics escapen a la regulaci\u00f3.<\/li>\n<li><strong> Perqu\u00e8 al contrari del que intenta l\u2019agroind\u00fastria, els pagesos ecol\u00f2gics\u00a0<\/strong>de Mallorca s\u00ed esteim a favor de la majoria de les mesures ambientals, agroecol\u00f2giques i de benestar animal que planteja Europa. No hi haur\u00e0 salut personal sense reduir agrot\u00f2xics, sense un ecosistema saludable i aliments lliures de verins.<\/li>\n<\/ol>\n<p>VISCA LA TERRA LLIURE I PAGESA!<\/p>\n<pre>Imatge: Uni\u00f3 de Pagesos<\/pre>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients<\/p>\n","protected":false},"author":1,"featured_media":87336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[692,955],"tags":[],"coauthors":[2053],"class_list":["post-87335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat","category-reportatges-i-novetats"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T11:57:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T23:20:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Manifestaci\u00f3 dels pagesos a Mallorca\",\"datePublished\":\"2024-02-19T11:57:23+00:00\",\"dateModified\":\"2024-02-21T23:20:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca\"},\"wordCount\":912,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/tractorada-19-febrer.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca\",\"name\":\"Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/tractorada-19-febrer.jpg\",\"datePublished\":\"2024-02-19T11:57:23+00:00\",\"dateModified\":\"2024-02-21T23:20:52+00:00\",\"description\":\"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients\",\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/manifestacio-dels-pagesos-a-mallorca#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/tractorada-19-febrer.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/tractorada-19-febrer.jpg\",\"width\":1201,\"height\":594},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament","description":"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca","og_locale":"ca_ES","og_type":"article","og_title":"Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament","og_description":"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients","og_url":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca","og_site_name":"Gastron\u00f2micament","article_published_time":"2024-02-19T11:57:23+00:00","article_modified_time":"2024-02-21T23:20:52+00:00","og_image":[{"width":1201,"height":594,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Manifestaci\u00f3 dels pagesos a Mallorca","datePublished":"2024-02-19T11:57:23+00:00","dateModified":"2024-02-21T23:20:52+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca"},"wordCount":912,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"ca-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca","url":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca","name":"Manifestaci\u00f3 dels pagesos a Mallorca - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg","datePublished":"2024-02-19T11:57:23+00:00","dateModified":"2024-02-21T23:20:52+00:00","description":"Manifestaci\u00f3 dels pagesos a Mallorca Actualitat, Reportatges i novetats El sector es mobilitza amb una tractorada per reclamar millores r\u00e0pides i eficients","inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/manifestacio-dels-pagesos-a-mallorca#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/tractorada-19-febrer.jpg","width":1201,"height":594},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/ca\/#website","url":"https:\/\/gastronomicament.cat\/ca\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/ca\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/ca\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/87335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/comments?post=87335"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/posts\/87335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media\/87336"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media?parent=87335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/categories?post=87335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/tags?post=87335"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/coauthors?post=87335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}