{"id":7057,"date":"2013-04-20T22:47:35","date_gmt":"2013-04-20T22:47:35","guid":{"rendered":"http:\/\/anardetapes.cat\/?p=7057"},"modified":"2022-04-07T11:17:14","modified_gmt":"2022-04-07T09:17:14","slug":"tallarines-de-mango-amb-salsa-de-maduixa","status":"publish","type":"recepta","link":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa","title":{"rendered":"Tallarines de mango amb salsa de maduixa"},"content":{"rendered":"<p><strong>Ingredients<\/strong><\/p>\n<ul>\n<li>1 mango<\/li>\n<li>Salsa de maduixes:<\/li>\n<li>500 g de maduixes<\/li>\n<li>\u00a0Un quart de culleradeta de sal<\/li>\n<li>Un quart de culleradeta de pebre negre<\/li>\n<li>5 cullerades de sucre<\/li>\n<\/ul>\n<p><strong>Elaboraci\u00f3<\/strong><br \/>\nTalleu un mango en l\u00e0mines fines i cada l\u00e0mina en tires. Poseu un grapat d&#8217;aquestes tallarines en un plat de manera que formi una muntanya i serviu-lo amb salsa de maduixa pel voltant.<br \/>\nPer fer la salsa de maduixes: Tritureu 500 g de maduixes amb un quart de culleradeta de sal, un quart de culleradeta de pebre negre i cinc cullerades de sucre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Talleu un mango en ll\u00e0mines fines i cada l\u00e0mina en tires. Poseu un grapat d&#8217;aquestes tallarines&hellip;<\/p>\n","protected":false},"author":30,"featured_media":7058,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[12],"concurs-mossegades":[745],"dificultat":[685],"ingredient":[746],"plat":[687],"preu-per-racio":[],"receptes-tematiques":[],"temps-de-preparacio":[],"coauthors":[],"class_list":["post-7057","recepta","type-recepta","status-publish","format-standard","has-post-thumbnail","hentry","category-receptes","concurs_receptes_mossegades-concurs-receptes-abril-2013","dificultat-mitjana","ingredient-maduixes","plat-postres"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tallarines de mango amb salsa de maduixa<\/title>\n<meta name=\"description\" content=\"Recepta:Tallarines de mango amb salsa de maduixa \/ Receta: Tallarines de mango con salsa de fresas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tallarines de mango amb salsa de maduixa\" \/>\n<meta property=\"og:description\" content=\"Recepta:Tallarines de mango amb salsa de maduixa \/ Receta: Tallarines de mango con salsa de fresas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T09:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2013\/04\/DSC\/DSCN1755.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan F. Jerez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa\",\"name\":\"Tallarines de mango amb salsa de maduixa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC\\\/DSCN1755.jpg\",\"datePublished\":\"2013-04-20T22:47:35+00:00\",\"dateModified\":\"2022-04-07T09:17:14+00:00\",\"description\":\"Recepta:Tallarines de mango amb salsa de maduixa \\\/ Receta: Tallarines de mango con salsa de fresas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC\\\/DSCN1755.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/DSC\\\/DSCN1755.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/recepta\\\/tallarines-de-mango-amb-salsa-de-maduixa#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Receptes\",\"item\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/receptes\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tallarines de mango amb salsa de maduixa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tallarines de mango amb salsa de maduixa","description":"Recepta:Tallarines de mango amb salsa de maduixa \/ Receta: Tallarines de mango con salsa de fresas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa","og_locale":"ca_ES","og_type":"article","og_title":"Tallarines de mango amb salsa de maduixa","og_description":"Recepta:Tallarines de mango amb salsa de maduixa \/ Receta: Tallarines de mango con salsa de fresas","og_url":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa","og_site_name":"Gastron\u00f2micament","article_modified_time":"2022-04-07T09:17:14+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2013\/04\/DSC\/DSCN1755.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Joan F. Jerez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa","url":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa","name":"Tallarines de mango amb salsa de maduixa","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2013\/04\/DSC\/DSCN1755.jpg","datePublished":"2013-04-20T22:47:35+00:00","dateModified":"2022-04-07T09:17:14+00:00","description":"Recepta:Tallarines de mango amb salsa de maduixa \/ Receta: Tallarines de mango con salsa de fresas","breadcrumb":{"@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa"]}]},{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2013\/04\/DSC\/DSCN1755.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2013\/04\/DSC\/DSCN1755.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/gastronomicament.cat\/ca\/recepta\/tallarines-de-mango-amb-salsa-de-maduixa#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Receptes","item":"https:\/\/gastronomicament.cat\/ca\/receptes"},{"@type":"ListItem","position":2,"name":"Tallarines de mango amb salsa de maduixa"}]},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/ca\/#website","url":"https:\/\/gastronomicament.cat\/ca\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/ca\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/recepta\/7057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/recepta"}],"about":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/types\/recepta"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/comments?post=7057"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/recepta\/7057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media\/7058"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/media?parent=7057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/categories?post=7057"},{"taxonomy":"concurs_receptes_mossegades","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/concurs-mossegades?post=7057"},{"taxonomy":"dificultat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/dificultat?post=7057"},{"taxonomy":"ingredient","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/ingredient?post=7057"},{"taxonomy":"plat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/plat?post=7057"},{"taxonomy":"preu_per_racio","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/preu-per-racio?post=7057"},{"taxonomy":"tematica","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/receptes-tematiques?post=7057"},{"taxonomy":"temps_de_preparacio","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/temps-de-preparacio?post=7057"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/ca\/wp-json\/wp\/v2\/coauthors?post=7057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}