{"id":102870,"date":"2025-10-16T06:53:35","date_gmt":"2025-10-16T04:53:35","guid":{"rendered":"https:\/\/web2025.gastronomicament.cat\/el-govern-inicia-la-campanya-dels-bons-de-producte-local"},"modified":"2026-04-16T14:19:13","modified_gmt":"2026-04-16T12:19:13","slug":"el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","title":{"rendered":"El Govern inicia la campanya dels Bons de Producte Local"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Conselleria d\u2019Agricultura, Pesca i Medi Natural ha inaugurat avui la campanya dels Bons de Producte Local, una iniciativa impulsada a trav\u00e9s de la Direcci\u00f3 General de Qualitat Agroaliment\u00e0ria i Producte Local i en col\u00b7laboraci\u00f3 amb la Cambra de Comer\u00e7 de Mallorca, amb l\u2019<strong>objectiu&nbsp;de fomentar el consum de producte local de les Illes Balears i refor\u00e7ar la relaci\u00f3 directa entre el productor i el consumidor<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquesta campanya&nbsp;<strong>s\u2019emmarca dins les accions extraordin\u00e0ries que ha posat en marxa el Govern de les Illes Balears per fer front a les conseq\u00fc\u00e8ncies negatives que pugui causar la situaci\u00f3 aranzel\u00e0ria entre els Estats Units i la Uni\u00f3 Europea sobre els productors locals<\/strong>. Es pret\u00e9n enfortir el consum intern de producte local per evitar que el sector primari depengui dels mercats exteriors.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Com puc aconseguir els meus abonaments?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir del 13 d\u2019octubre, les persones majors de 16 anys amb document nacional d\u2019identitat, nombre d\u2019identificaci\u00f3 d\u2019estranger o passaport podran adquirir un producte d\u2019un dels establiments comercials adherits a la campanya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Els bons s\u2019adquireixen en el propi establiment on es vol fer la compra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa permet als consumidors obtenir un descompte de 10 euros per cada 20 euros de compra, fins a un m\u00e0xim de 60 euros, en establiments participants de totes les illes.<strong>&nbsp;El consumidor no ha de fer cap inscripci\u00f3 ni sol\u00b7licitud pr\u00e8via; simplement s\u2019ha d\u2019identificar amb el DNI, NIE o passaport en el moment de la compra<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Omplir el rebost amb producte local<br>\n<\/strong>L\u2019acte d\u2019inici s\u2019ha celebrat a la Cooperativa Pagesa de Pollen\u00e7a, un dels establiments adherits a la campanya, i ha comptat amb la pres\u00e8ncia del conseller&nbsp;<strong>Joan Simonet<\/strong>; el director general de Qualitat Agroaliment\u00e0ria i Producte Local,&nbsp;<strong>Joan Llabr\u00e9s<\/strong>; el batle de Pollen\u00e7a,&nbsp;<strong>Mart\u00ed March<\/strong>; la presidenta de la Comissi\u00f3 de Comer\u00e7 de la Cambra de Comer\u00e7 de Mallorca,&nbsp;<strong>Joana Manresa<\/strong>, i el president de la cooperativa,&nbsp;<strong>Mart\u00ed Solivellas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conseller d\u2019Agricultura, Pesca i Medi Natural, Joan Simonet, ha destacat que aquesta campanya \u00e9s una \u00abconvidada a tota la ciutadania perqu\u00e8 ompli el seu rebost amb producte d\u2019aqu\u00ed; cada compra&nbsp;<strong>\u00e9s una manera directa de donar suport als nostres agricultors, ramaders i elaboradors<\/strong>\u00bb. A m\u00e9s, ha afegit que \u00abel producte local \u00e9s sin\u00f2nim de qualitat, sostenibilitat i territori; consumir-lo \u00e9s apostar pel futur del camp i de la nostra economia\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per la seva banda, el director general Joan Llabr\u00e9s ha remarcat que \u00abs\u2019ha obtingut una resposta molt bona per part del sector productor.&nbsp;<strong>Es percep la voluntat i la necessitat de contactar directament amb el consumidor<\/strong>, i amb aquesta iniciativa volem donar resposta a la demanda del sector d\u2019incrementar el coneixement i la comercialitzaci\u00f3 del producte local\u00bb. De fet, segons ha subratllat Llabr\u00e9s, en les primeres hores ja s&#8217;havien canviat prop de mil bons.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En total,<strong>&nbsp;la campanya t\u00e9 100 establiments inscrits<\/strong>, dels quals 51 s\u00f3n explotacions agr\u00e0ries, cooperatives o societats agr\u00e0ries de transformaci\u00f3, i 36 corresponen a ind\u00fastries aliment\u00e0ries. Per illes, hi participen 75 productors de Mallorca, 7 de Menorca i 5 d\u2019Eivissa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Els&nbsp;<strong>productes disponibles<\/strong>&nbsp;abracen una \u00e0mplia varietat i es podran trobar en nombrosos establiments: fruita i hortalissa (26), carn i embotits (22), formatges i lactis (19), vi (53), oli i olives (23), mel (20), confitures i conserves (21), fruits secs (12), pa i farina (8), begudes espirituoses (14) i altres productes locals (23).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tots els&nbsp;<strong>establiments adherits es poden consultar al web<\/strong>:&nbsp;<a href=\"http:\/\/www.bonsproductelocal.com\/llistat-destabliments-adherits\" target=\"_blank\" rel=\"noopener nofollow\">www.bonsproductelocal.com\/llistat-destabliments-adherits<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aquest sentit, el president de la cooperativa,<strong>&nbsp;Mart\u00ed Solivellas<\/strong>, ha afirmat que \u00ab\u00e9s una iniciativa fant\u00e0stica i molt ben rebuda pels productors\u00bb. Per la seva banda, des de la Cambra de Comer\u00e7, la presidenta de la Comissi\u00f3,&nbsp;<strong>Joana Manresa<\/strong>, ha recalcat que \u00abno ens haur\u00edem de permetre importar de fora all\u00f2 que ja produ\u00efm aqu\u00ed, amb una qualitat excel\u00b7lent\u00bb. Per aix\u00f2, ha animat la ciutadania a participar en aquesta campanya, a comprar i con\u00e8ixer el producte local, una elecci\u00f3 que representa \u00abqualitat, sabor i sostenibilitat\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La campanya t\u00e9 un finan\u00e7ament de 363.700 euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per beneficiar-se&#8217;n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits<\/p>\n","protected":false},"author":1,"featured_media":102873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[692,955],"tags":[],"coauthors":[2053],"class_list":["post-102870","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat","category-reportatges-i-novetats","post_format-post-format-gallery"],"acf":{"gallery":[102882,102872],"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se&#039;n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se&#039;n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T04:53:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T12:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"961\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"El Govern inicia la campanya dels Bons de Producte Local\",\"datePublished\":\"2025-10-16T04:53:35+00:00\",\"dateModified\":\"2026-04-16T12:19:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\"},\"wordCount\":709,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\",\"name\":\"El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg\",\"datePublished\":\"2025-10-16T04:53:35+00:00\",\"dateModified\":\"2026-04-16T12:19:13+00:00\",\"description\":\"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se'n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg\",\"width\":1599,\"height\":961},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament","description":"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se'n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","og_locale":"de_DE","og_type":"article","og_title":"El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament","og_description":"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se'n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits","og_url":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","og_site_name":"Gastron\u00f2micament","article_published_time":"2025-10-16T04:53:35+00:00","article_modified_time":"2026-04-16T12:19:13+00:00","og_image":[{"width":1599,"height":961,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Verfasst von":"Redacci\u00f3","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"El Govern inicia la campanya dels Bons de Producte Local","datePublished":"2025-10-16T04:53:35+00:00","dateModified":"2026-04-16T12:19:13+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2"},"wordCount":709,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","url":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2","name":"El Govern inicia la campanya dels Bons de Producte Local - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg","datePublished":"2025-10-16T04:53:35+00:00","dateModified":"2026-04-16T12:19:13+00:00","description":"El Govern inicia la campanya dels Bons de Producte Local Actualitat, Reportatges i novetats Per beneficiar-se'n, no cal descarregar cap document, nom\u00e9s cal anar als establiments inscrits","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/el-govern-inicia-la-campanya-dels-bons-de-producte-local-2#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2025\/10\/Bons-Producte-Local-Illes-Balears-2025-Aliments-1.jpg","width":1599,"height":961},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/102870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/comments?post=102870"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/102870\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/102872"},{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/102882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/102873"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media?parent=102870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/categories?post=102870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/tags?post=102870"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/coauthors?post=102870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}