{"id":57876,"date":"2021-09-16T10:31:33","date_gmt":"2021-09-16T08:31:33","guid":{"rendered":"https:\/\/gastronomicament.cat\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda"},"modified":"2022-04-09T09:24:02","modified_gmt":"2022-04-09T07:24:02","slug":"es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","title":{"rendered":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda"},"content":{"rendered":"<p>Jaume Alzamora, conseller de Promoci\u00f3 Econ\u00f2mica i Desenvolupament Local, ha visitat aquest dimecres,\u00a0<strong>Es Forn des Pla de na Tesa<\/strong>. Aquest establiment t\u00e9\u00a0<strong>122 anys d\u2019hist\u00f2ria<\/strong>\u00a0i que actualment est\u00e0 regentat per\u00a0<strong>Maties i Jaume Miralles<\/strong>, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal.<\/p>\n<p>Es Forn des Pla de na Tesa ja ha gaudit de l\u2019ajuda del Consell de Mallorca per adquirir nova maquin\u00e0ria, gr\u00e0cies a les subvencions anuals de la Direcci\u00f3 Insular d\u2019Artesania. Aquesta l\u00ednia d&#8217;actuaci\u00f3 \u00e9s una de les principals del Consell per contribuir a la millora de la competitivitat dels obradors i tallers artesans, cosa que tamb\u00e9 influeix en la professionalitzaci\u00f3 dels mateixos artesans.<\/p>\n<p><strong>Un futur nou Mestre Artes\u00e0?<br \/>\n<\/strong>D&#8217;altra banda, la Pon\u00e8ncia T\u00e8cnica d\u2019Artesania del Consell de Mallorca avaluar\u00e0 pr\u00f2ximament el pastisser Maties Miralles per atorgar-li la carta d\u2019artes\u00e0 i acreditar de manera oficial que, com son pare (ja mestre artes\u00e0), elabora productes de manera artesanal.<\/p>\n<p>Els germans Miralles aposten per la tradici\u00f3 alhora que treballen productes d\u2019avantguarda, que fan que el seu negoci mantengui l\u2019atractiu entre les generacions m\u00e9s joves d\u2019arreu de l\u2019illa. En aquest sentit, cal dir que\u00a0<strong>Maties Miralles \u00e9s finalista a la Copa del M\u00f3n del Panettone<\/strong>, que se celebrar\u00e0 a Lugano (Su\u00efssa) el mes de novembre. Es tracta d\u2019un producte t\u00edpic itali\u00e0 que Es Forn comercialitza juntament amb altres productes de Mallorca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3&hellip;<\/p>\n","protected":false},"author":1,"featured_media":57877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1050,1476],"tags":[],"coauthors":[],"class_list":["post-57876","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat-es-de","category-reportatges-i-novetats-de","post_format-post-format-gallery"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T08:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-09T07:24:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda\",\"datePublished\":\"2021-09-16T08:31:33+00:00\",\"dateModified\":\"2022-04-09T07:24:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\",\"name\":\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg\",\"datePublished\":\"2021-09-16T08:31:33+00:00\",\"dateModified\":\"2022-04-09T07:24:02+00:00\",\"description\":\"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament","description":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","og_locale":"de_DE","og_type":"article","og_title":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament","og_description":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal","og_url":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","og_site_name":"Gastron\u00f2micament","article_published_time":"2021-09-16T08:31:33+00:00","article_modified_time":"2022-04-09T07:24:02+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Verfasst von":"Redacci\u00f3","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda","datePublished":"2021-09-16T08:31:33+00:00","dateModified":"2022-04-09T07:24:02+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/de\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","url":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda","name":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg","datePublished":"2021-09-16T08:31:33+00:00","dateModified":"2022-04-09T07:24:02+00:00","description":"Es Forn des Pla de na Tesa: Tradici\u00f3 i avantguarda Actualitat, Reportatges i novetats Aquest establiment t\u00e9\u00a0122 anys d\u2019hist\u00f2ria\u00a0i que actualment est\u00e0 regentat per\u00a0Maties i Jaume Miralles, la tercera generaci\u00f3 d\u2019una fam\u00edlia amb tradici\u00f3 artesanal","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/es-forn-des-pla-de-na-tesa-tradicio-i-avantguarda#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2021\/09\/Ensaimada-de-figues-i-sobrassada-Forn-Pla-de-na-Tesa.jpg","width":1600,"height":1067},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/de\/#website","url":"https:\/\/gastronomicament.cat\/de\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/de\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/57876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/comments?post=57876"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/57876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/57877"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media?parent=57876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/categories?post=57876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/tags?post=57876"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/coauthors?post=57876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}