{"id":63272,"date":"2019-08-08T11:41:58","date_gmt":"2019-08-08T09:41:58","guid":{"rendered":"https:\/\/gastronomicament.cat\/carnabars-i-sopar-a-la-fresca-a-puigpunyent"},"modified":"2022-04-09T09:50:54","modified_gmt":"2022-04-09T07:50:54","slug":"carnabars-i-sopar-a-la-fresca-a-puigpunyent","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent","title":{"rendered":"Carnabars i sopar a la fresca a Puigpunyent"},"content":{"rendered":"<p>En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d&#8217;Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d&#8217;activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia.<\/p>\n<p>El divendres dia 9 hi haur\u00e0 el <strong>Carnabars<\/strong>, una dels actes m\u00e9s animats amb petits concerts als bars de Puigpunyent. Enguany es recorden els anys 60, aix\u00ed que per assistir-hi disfressa&#8217;t amb les millors peces de roba que tenguis d&#8217;aquesta \u00e8poca. Les actuacions que hi haur\u00e0 s\u00f3n les seg\u00fcents:<\/p>\n<ul>\n<li>23:30 Bar Es Pont amb Dj Kaasi<\/li>\n<li>01:00 Can Jordi amb Dimecres Rock<\/li>\n<li>02:30 Bar de Festes amb Tom Trovador<\/li>\n<\/ul>\n<p>A m\u00e9s a m\u00e9s, el dissabte 10 d&#8217;agost , hi haur\u00e0 el sopar a la fresca. Els tiquets s&#8217;han de comprar a l&#8217;Ajuntament de Puigpunyent com a tard el 8 d&#8217;agost. El preu per al sopar \u00e9s de 8 euros. Pensau que hi heu de dur plat, tass\u00f3 i coberts reutilitzables. Els restaurants de Puigpunyent participants i els plats que cuinaran s\u00f3n:<\/p>\n<p><strong>Ses Cotxeries<\/strong><\/p>\n<ul>\n<li>Alberg\u00ednies farcides de carn<\/li>\n<li>Alberg\u00ednies farcides de verdures<\/li>\n<li>Coca de patata d&#8217;albercoc<\/li>\n<\/ul>\n<p><strong>Can Jordi<\/strong><\/p>\n<ul>\n<li>Frit de s\u00edpia<\/li>\n<li>Past\u00eds de pastanaga<\/li>\n<\/ul>\n<p><strong>Es Pont<\/strong><\/p>\n<ul>\n<li>Frit de xot<\/li>\n<li>Glopet de gaspatxo de s\u00edndria<\/li>\n<\/ul>\n<p><strong>The Rose Bistro<\/strong><\/p>\n<ul>\n<li>Goulash amb arr\u00f2s<\/li>\n<li>Gelat<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":63273,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1050,1473],"tags":[],"coauthors":[],"class_list":["post-63272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat-es-de","category-fires-i-rutes-de"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d&#039;Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d&#039;activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d&#039;Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d&#039;activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-08T09:41:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-09T07:50:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"781\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Carnabars i sopar a la fresca a Puigpunyent\",\"datePublished\":\"2019-08-08T09:41:58+00:00\",\"dateModified\":\"2022-04-09T07:50:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Portada-Festes-Puigpunyent-2019.jpg\",\"articleSection\":[\"Actualitat\",\"Fires i rutes\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\",\"name\":\"Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Portada-Festes-Puigpunyent-2019.jpg\",\"datePublished\":\"2019-08-08T09:41:58+00:00\",\"dateModified\":\"2022-04-09T07:50:54+00:00\",\"description\":\"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d'Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d'activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Portada-Festes-Puigpunyent-2019.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Portada-Festes-Puigpunyent-2019.jpg\",\"width\":781,\"height\":405},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament","description":"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d'Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d'activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent","og_locale":"de_DE","og_type":"article","og_title":"Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament","og_description":"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d'Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d'activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia","og_url":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent","og_site_name":"Gastron\u00f2micament","article_published_time":"2019-08-08T09:41:58+00:00","article_modified_time":"2022-04-09T07:50:54+00:00","og_image":[{"width":781,"height":405,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Verfasst von":"Redacci\u00f3","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Carnabars i sopar a la fresca a Puigpunyent","datePublished":"2019-08-08T09:41:58+00:00","dateModified":"2022-04-09T07:50:54+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/de\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg","articleSection":["Actualitat","Fires i rutes"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent","url":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent","name":"Carnabars i sopar a la fresca a Puigpunyent - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg","datePublished":"2019-08-08T09:41:58+00:00","dateModified":"2022-04-09T07:50:54+00:00","description":"Carnabars i sopar a la fresca a Puigpunyent Actualitat, Fires i rutes En motiu de les festes del patr\u00f3 i la patrona de Puigpunyent, Sant Roc i la Mare de D\u00e9u d'Agost, aquest municipi de la Serra de Tramuntana organitza un programa ben carregat d'activitats en qu\u00e8 la participaci\u00f3 popular hi t\u00e9 molta import\u00e0ncia","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/carnabars-i-sopar-a-la-fresca-a-puigpunyent#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2019\/08\/Portada-Festes-Puigpunyent-2019.jpg","width":781,"height":405},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/de\/#website","url":"https:\/\/gastronomicament.cat\/de\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/de\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/63272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/comments?post=63272"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/posts\/63272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/63273"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media?parent=63272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/categories?post=63272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/tags?post=63272"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/coauthors?post=63272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}