{"id":53773,"date":"2017-07-20T12:33:23","date_gmt":"2017-07-20T10:33:23","guid":{"rendered":"https:\/\/gastronomicament.cat\/restaurant\/posada-del-marques-esporles"},"modified":"2023-10-04T14:40:26","modified_gmt":"2023-10-04T12:40:26","slug":"posada-del-marques-esporles","status":"publish","type":"restaurant","link":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles","title":{"rendered":"Posada del Marqu\u00e8s"},"content":{"rendered":"<p>Aquest hotel encantador d&#8217;Esporles ofereix un entorn tranquil una cuina suggerent i selecta en un ambient distingit. El restaurant de La Posada del Marqu\u00e8s ofereix una experi\u00e8ncia gastron\u00f2mica molt suculenta en dos espais ben diferenciats: la majestuosa tafona o la meravellosa terrassa amb vista a la Serra de Tramuntana.<\/p>\n<p>Hi trobareu una selecci\u00f3 de plats, a destacar les paelles, com tamb\u00e9 ensalades, carn, peix i una carta de vins mallorquins. Un restaurant rom\u00e0ntic que tamb\u00e9 convida a viure una vetlada rom\u00e0ntica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquest hotel encantador d&#8217;Esporles ofereix un entorn tranquil una cuina suggerent i selecta en un ambient distingit. El restaurant de La Posada del Marqu\u00e8s ofereix una experi\u00e8ncia gastron\u00f2mica molt suculenta en dos espais ben diferenciats: la majestuosa tafona o la meravellosa terrassa amb vista a la Serra de Tramuntana. Hi trobareu una selecci\u00f3 de plats, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53774,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"direccio":"Es Verger, s\/n","telefon":"971 61 12 30","web":"","horari":"","preumitja":"","observacions":"","footnotes":""},"categories":[1029],"destacatper":[],"especialitat":[1162,1060],"localitat":[1375,1033,1118],"coauthors":[],"class_list":["post-53773","restaurant","type-restaurant","status-publish","format-gallery","has-post-thumbnail","hentry","category-restaurants-es-de","especialitat-arrosseria-de","especialitat-cuina-selecta-de","localitat-esporles-de","localitat-mallorca-de","localitat-tramuntana-de","preu-mes-de-30-euros-de"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posada del Marqu\u00e8s - Gastron\u00f2micament<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posada del Marqu\u00e8s - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Aquest hotel encantador d&#8217;Esporles ofereix un entorn tranquil una cuina suggerent i selecta en un ambient distingit. El restaurant de La Posada del Marqu\u00e8s ofereix una experi\u00e8ncia gastron\u00f2mica molt suculenta en dos espais ben diferenciats: la majestuosa tafona o la meravellosa terrassa amb vista a la Serra de Tramuntana. Hi trobareu una selecci\u00f3 de plats, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T12:40:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/07\/Restaurant-Posada-del-Marques-Esporles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles\",\"name\":\"Posada del Marqu\u00e8s - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Restaurant-Posada-del-Marques-Esporles.jpg\",\"datePublished\":\"2017-07-20T10:33:23+00:00\",\"dateModified\":\"2023-10-04T12:40:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Restaurant-Posada-del-Marques-Esporles.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Restaurant-Posada-del-Marques-Esporles.jpg\",\"width\":1800,\"height\":1202},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurant\\\/posada-del-marques-esporles#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Restaurants\",\"item\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/restaurants\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Posada del Marqu\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posada del Marqu\u00e8s - Gastron\u00f2micament","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles","og_locale":"de_DE","og_type":"article","og_title":"Posada del Marqu\u00e8s - Gastron\u00f2micament","og_description":"Aquest hotel encantador d&#8217;Esporles ofereix un entorn tranquil una cuina suggerent i selecta en un ambient distingit. El restaurant de La Posada del Marqu\u00e8s ofereix una experi\u00e8ncia gastron\u00f2mica molt suculenta en dos espais ben diferenciats: la majestuosa tafona o la meravellosa terrassa amb vista a la Serra de Tramuntana. Hi trobareu una selecci\u00f3 de plats, [&hellip;]","og_url":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles","og_site_name":"Gastron\u00f2micament","article_modified_time":"2023-10-04T12:40:26+00:00","og_image":[{"width":1800,"height":1202,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/07\/Restaurant-Posada-del-Marques-Esporles.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles","url":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles","name":"Posada del Marqu\u00e8s - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/07\/Restaurant-Posada-del-Marques-Esporles.jpg","datePublished":"2017-07-20T10:33:23+00:00","dateModified":"2023-10-04T12:40:26+00:00","breadcrumb":{"@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/07\/Restaurant-Posada-del-Marques-Esporles.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/07\/Restaurant-Posada-del-Marques-Esporles.jpg","width":1800,"height":1202},{"@type":"BreadcrumbList","@id":"https:\/\/gastronomicament.cat\/de\/restaurant\/posada-del-marques-esporles#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Restaurants","item":"https:\/\/gastronomicament.cat\/de\/restaurants"},{"@type":"ListItem","position":2,"name":"Posada del Marqu\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/de\/#website","url":"https:\/\/gastronomicament.cat\/de\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/de\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/restaurant\/53773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/types\/restaurant"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/comments?post=53773"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/restaurant\/53773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media\/53774"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/media?parent=53773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/categories?post=53773"},{"taxonomy":"destacatper","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/destacatper?post=53773"},{"taxonomy":"especialitat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/especialitat?post=53773"},{"taxonomy":"localitat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/localitat?post=53773"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/de\/wp-json\/wp\/v2\/coauthors?post=53773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}