{"id":104702,"date":"2026-05-13T11:47:53","date_gmt":"2026-05-13T09:47:53","guid":{"rendered":"https:\/\/gastronomicament.cat\/?p=104702"},"modified":"2026-05-13T11:48:30","modified_gmt":"2026-05-13T09:48:30","slug":"la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia","title":{"rendered":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia"},"content":{"rendered":"\n<p>La cuinera Macarena de Castro ha rebut el II premi Sobrassada d\u2019Or &#8211; Excel\u00b7l\u00e8ncia de Mallorca 2026. En un acte celebrat a Ca\u2019n T\u00e0pera, la IGP Sobrassada de Mallorca i el Consell de Mallorca han reconegut la xef com la millor ambaixadora de la identitat culin\u00e0ria de l\u2019illa.<br><br>El president del Consell, Lloren\u00e7 Galm\u00e9s, ha destacat la traject\u00f2ria d&#8217;una dona que ha situat la gastronomia mallorquina al capdamunt \u00absense perdre mai les arrels\u00bb, mentre que Andreu Palou, president de la IGP Sobrassada, ha recordat que la cuina de De Castro \u00abexplica el paisatge, la mem\u00f2ria i el mar\u00bb. Per la seva banda, la consellera Pilar Amate ha subratllat que la xef cerca constantment l&#8217;autenticitat i el suport al sector primari.<br><br><strong>Un guard\u00f3 amb pes i hist\u00f2ria<br><\/strong>El premi \u00e9s una escultura de ferro forjat i pedra de l&#8217;<strong>artista Jaume Canet<\/strong>. Representa un&nbsp;<strong>bisbe<\/strong>, la varietat de sobrassada m\u00e9s grossa (pot fer entre 4 i 30 quilos) i de curaci\u00f3 m\u00e9s lenta (de devers 4 mesos de maduraci\u00f3), que \u00e9s un s\u00edmbol de la paci\u00e8ncia i el rigor que De Castro aplica als seus fogons.<br><br><strong>Cuinar amb llibertat<br><\/strong>Visiblement emocionada, Maca de Castro ha dedicat el premi als productors i ramaders: \u00abLa nostra cuina neix d&#8217;una connexi\u00f3 real amb el camp; mantenir viva la tradici\u00f3 i cuinar amb llibertat \u00e9s el que dona sentit al nostre ofici\u00bb.&nbsp; Nascuda a Mallorca el 1981, Macarena de Castro lidera el restaurant que duu el seu nom al Port d&#8217;Alc\u00fadia. La seva traject\u00f2ria, definida per un lligam visceral amb el receptari mallorqu\u00ed i una mirada contempor\u00e0nia, l&#8217;ha consolidada com una de les figures m\u00e9s influents de la gastronomia actual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca&hellip;<\/p>\n","protected":false},"author":1,"featured_media":104703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[692,940,955],"tags":[],"coauthors":[2053],"class_list":["post-104702","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat","category-inici","category-reportatges-i-novetats","post_format-post-format-gallery"],"acf":{"gallery":[104703,104707],"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel\u00b7lencia\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel\u00b7lencia\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T09:47:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T09:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1594\" \/>\n\t<meta property=\"og:image:height\" content=\"977\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia\",\"datePublished\":\"2026-05-13T09:47:53+00:00\",\"dateModified\":\"2026-05-13T09:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg\",\"articleSection\":[\"Actualitat\",\"Portada\",\"Reportatges i novetats\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia\",\"name\":\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg\",\"datePublished\":\"2026-05-13T09:47:53+00:00\",\"dateModified\":\"2026-05-13T09:48:30+00:00\",\"description\":\"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg\",\"width\":1594,\"height\":977},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament","description":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel\u00b7lencia","og_locale":"en_US","og_type":"article","og_title":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament","og_description":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.","og_url":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel\u00b7lencia","og_site_name":"Gastron\u00f2micament","article_published_time":"2026-05-13T09:47:53+00:00","article_modified_time":"2026-05-13T09:48:30+00:00","og_image":[{"width":1594,"height":977,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia","datePublished":"2026-05-13T09:47:53+00:00","dateModified":"2026-05-13T09:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/en\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg","articleSection":["Actualitat","Portada","Reportatges i novetats"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia","url":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia","name":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg","datePublished":"2026-05-13T09:47:53+00:00","dateModified":"2026-05-13T09:48:30+00:00","description":"La Sobrassada d\u2019Or corona Maca de Castro per la seva excel\u00b7l\u00e8ncia Actualitat, Portada, Reportatges i novetats La xef del Port d\u2019Alc\u00fadia rep el guard\u00f3 de la IGP i el Consell de Mallorca pel seu comprom\u00eds inalterable amb el territori.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/en\/la-sobrassada-dor-corona-maca-de-castro-per-la-seva-excel%c2%b7lencia#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2026\/05\/Maca-de-Castro-Sobrassada-d-Or-Mallorca.jpg","width":1594,"height":977},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/en\/#website","url":"https:\/\/gastronomicament.cat\/en\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/en\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/en\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/104702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/comments?post=104702"}],"version-history":[{"count":1,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/104702\/revisions"}],"predecessor-version":[{"id":104711,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/104702\/revisions\/104711"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media\/104707"},{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media\/104703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media\/104703"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media?parent=104702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/categories?post=104702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/tags?post=104702"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/coauthors?post=104702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}