{"id":70633,"date":"2015-08-11T02:07:15","date_gmt":"2015-08-11T00:07:15","guid":{"rendered":"https:\/\/gastronomicament.cat\/ruta-de-la-tapa-casa-miss-de-sa-pobla"},"modified":"2015-08-11T02:07:15","modified_gmt":"2015-08-11T00:07:15","slug":"ruta-de-la-tapa-casa-miss-de-sa-pobla","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla","title":{"rendered":"Ruta de la Tapa a Casa Miss de sa Pobla"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignleft\" style=\"margin: 7px;\" title=\"Ruta de la Tapa a sa Pobla Casa Miss\" src=\"http:\/\/gastronomicament.cat\/wp-content\/uploads\/2014\/05\/cartell-ruta-de-la-tapa-sa-pobla-casa-miss.jpg\" alt=\"\" width=\"206\" height=\"432\" \/>Cada dimecres vespre, el <a title=\"Casa Miss sa Pobla\" href=\"http:\/\/gastronomicament.cat\/restaurant-casa-miss\">restaurant Casa Miss de sa Pobla<\/a> hi trobareu molt bon ambient i tapes a <strong>nom\u00e9s 1 euro<\/strong>.<\/p>\n<p>A la Ruta de la Tapa a Casa Miss de sa Pobla hi trobareu m\u00e9s de 35 picades!<\/p>\n<p>Algunes de les tapes i barquetes que hi trobareu s\u00f3n:<\/p>\n<ul>\n<li>Barqueta de pollastre amb xampinyons<\/li>\n<li>Maxicroquetes de pernil ib\u00e8ric<\/li>\n<li>Formatge arrebossat amb confitura<\/li>\n<li>Barqueta de vedella amb mostassa de Dij\u00f3n, confitura i ceba confitada<\/li>\n<li>Mini coulant<\/li>\n<\/ul>\n<p>De 19 a 23 hores.<\/p>\n<p>La cervesa i el vi per nom\u00e9s 1 euro!<\/p>\n<p>Podeu reservar-hi taula al 696479710 o al 971540023.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada dimecres vespre, el restaurant Casa Miss de sa Pobla hi trobareu molt bon ambient i tapes a nom\u00e9s 1 euro. A la Ruta de la Tapa a Casa Miss de sa Pobla hi trobareu m\u00e9s de 35 picades! Algunes de les tapes i barquetes que hi trobareu s\u00f3n: Barqueta de pollastre amb xampinyons Maxicroquetes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54954,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1046],"tags":[],"coauthors":[],"class_list":["post-70633","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat-es-en","post_format-post-format-gallery"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ruta de la Tapa a Casa Miss de sa Pobla<\/title>\n<meta name=\"description\" content=\"Ruta de la Tapa a Casa Miss de sa Pobla\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ruta de la Tapa a Casa Miss de sa Pobla\" \/>\n<meta property=\"og:description\" content=\"Ruta de la Tapa a Casa Miss de sa Pobla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-11T00:07:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Ruta de la Tapa a Casa Miss de sa Pobla\",\"datePublished\":\"2015-08-11T00:07:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla\"},\"wordCount\":106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg\",\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla\",\"name\":\"Ruta de la Tapa a Casa Miss de sa Pobla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg\",\"datePublished\":\"2015-08-11T00:07:15+00:00\",\"description\":\"Ruta de la Tapa a Casa Miss de sa Pobla\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg\",\"width\":720,\"height\":405},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ruta de la Tapa a Casa Miss de sa Pobla","description":"Ruta de la Tapa a Casa Miss de sa Pobla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla","og_locale":"en_US","og_type":"article","og_title":"Ruta de la Tapa a Casa Miss de sa Pobla","og_description":"Ruta de la Tapa a Casa Miss de sa Pobla","og_url":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla","og_site_name":"Gastron\u00f2micament","article_published_time":"2015-08-11T00:07:15+00:00","og_image":[{"width":720,"height":405,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Ruta de la Tapa a Casa Miss de sa Pobla","datePublished":"2015-08-11T00:07:15+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla"},"wordCount":106,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/en\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg","articleSection":["Actualitat"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla","url":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla","name":"Ruta de la Tapa a Casa Miss de sa Pobla","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg","datePublished":"2015-08-11T00:07:15+00:00","description":"Ruta de la Tapa a Casa Miss de sa Pobla","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/en\/ruta-de-la-tapa-casa-miss-de-sa-pobla#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/08\/casa-miss-a-sa-pobla-ruta-de-la-tapa.jpg","width":720,"height":405},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/en\/#website","url":"https:\/\/gastronomicament.cat\/en\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/en\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/en\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/en\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/70633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/comments?post=70633"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/70633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media\/54954"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media?parent=70633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/categories?post=70633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/tags?post=70633"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/coauthors?post=70633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}