{"id":86871,"date":"2024-01-11T09:40:00","date_gmt":"2024-01-11T08:40:00","guid":{"rendered":"https:\/\/gastronomicament.cat\/temps-despinagades-a-mallorca"},"modified":"2024-01-11T09:40:00","modified_gmt":"2024-01-11T08:40:00","slug":"temps-despinagades-a-mallorca","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca","title":{"rendered":"Temps d&#8217;espinagades a Mallorca"},"content":{"rendered":"<p>La comarca del Raiguer de Mallorca celebra Sant Antoni amb una menja ben t\u00edpica: les espinagades. La fama d&#8217;aquesta pasta salada farcida d&#8217;anguila o de llom s&#8217;ha est\u00e8s per gaireb\u00e9 tot Mallorca.<\/p>\n<p>De fet, en podeu trobar a diferents forns, cafeteries i restaurants.<\/p>\n<p>Comen\u00e7arem recomanant un restaurant que \u00e9s tot un emblema de\u00a0<strong>sa Pobla<\/strong>. Es tracta del centenari\u00a0<strong>Bar des Tren<\/strong>. Les seves espinagades, plenes de sabor i textura, s\u00f3n l&#8217;acompanyament ideal per a aquestes dates. Recordau que cada dissabte i per enc\u00e0rrec es poden demanar espinagades per endur, per berenar o dinar. Reservau-ne\u00a0al \u00a0971540022.<\/p>\n<p>Una bona mostra \u00e9s el bar\u00a0<strong>Can Murt\u00f3 de Binissalem<\/strong>. Aix\u00ed ho diuen els seus responsables: &#8220;ja ens preparam per Sant Antoni amb un especial espinagades 2024, ja podeu fer el vostre enc\u00e0rrec (amb dos dies d&#8217;antelaci\u00f3) per als propers dies. Telefonau\u00a0o enviau un missatge al 608 90 61 02&#8221;. Hi trobareu espinagada de llom a 20 euros. Unitats limitades.<\/p>\n<p>Un altre lloc on podeu anar \u00e9s al\u00a0<strong>Forn i Pastisseria Gelabert, de Llub\u00ed<\/strong>. En fan de quatre castes: espinagada d&#8217;anguila, espinagada de mussola, espinagada de llom i espinagada de llom amb col. Les unitats s\u00f3n limitades i demanen que els encarrecs es facin amb antelaci\u00f3. Les podeu comanar a per tel\u00e8fon al 971 52 26 13 o per Whatsapp al 621 22 99 97.<\/p>\n<p>A\u00a0<strong>Palma<\/strong>, el\u00a0<strong>Fornet de la Soca<\/strong>\u00a0fa espinagades de dues mides: individuals i de grosses (per a 4-5 persones). Les fa farcides de quatre maneres diferents: de llom amb col, de mussola, d&#8217;anguila i la versi\u00f3 vegana. Podeu fer les comandes al 673 49 94 46.<\/p>\n<p>La persona que ha popularitzat les espinagades m\u00e9s enll\u00e0 de sa Pobla \u00e9s el cuiner i cap de sala\u00a0<strong>Pep Socies<\/strong>. Enguany, tamb\u00e9 en far\u00e0 per comanda.N&#8217;hi haur\u00e0 de dues castes: de col i llom (30 euros) i d&#8217;anguiles (37 euros). S\u00f3n de pasta fina i ben farcides. &#8220;Qui en vulgui\u00a0<strong>per dia 26\u00a0<\/strong>i vengui a cercar-les a\u00a0<strong>Pollen\u00e7a<\/strong>, ja m\u2019ho dir\u00e0 al 639424210&#8243;. Us en llepareu els dits!<\/p>\n<p>La dita diu: festes passades coques menjades. Ara b\u00e9, aix\u00f2 sembla que no s&#8217;atura. Al\u00a0<strong>Forn Can Rafel de B\u00fager<\/strong>\u00a0hi trobareu propostes ben dolces amb tem\u00e0tica de Sant Antoni: Dimonis\u00a0fets de pasta brisa amb una capa de Ferrero, merenga i xocolata. i Sant Antonis\u00a0fets de bescuit borratxo amb confitura d&#8217;albercocs, merenga i xocolata. Tamb\u00e9 hi trobareu espinagades ben bones! Comandes al 971 51 62 13.<\/p>\n<p>A\u00a0<strong>Palma<\/strong>, un altre forn que en podeu trobar i comanar \u00e9s la<strong>\u00a0Pastisseria Rialfa<\/strong>. Es troba al\u00a0C\/Francesc Sancho, n\u00famero 17. En fan de llom i de mussola fresca. En podeu fer els enc\u00e0rrecs al 661 109 611.<\/p>\n<p>El<strong>\u00a0Bip-Bip Ca na Maria\u00a0<\/strong>de\u00a0<strong>Muro\u00a0<\/strong>\u00e9s un supermercat on hi trobareu espinagades. En trobareu del 13 al 17 de gener i n&#8217;hi ha d&#8217;anguiles, de mussola, de llom i de verdures.<\/p>\n<p>Al\u00a0<strong>Port d&#8217;Alc\u00fadia<\/strong>, un altre lloc on en podeu trobar \u00e9s al\u00a0<strong>Forn Can Joan Serra\u00a0<\/strong>(carrer dels Pins, 2). Important, \u00e9s dels pocs establiments que en trobrareu de s\u00edpia. Tamb\u00e9, en fan de llom. M\u00e9s informaci\u00f3 al 971 54 53 51.<\/p>\n<p>Un altre temple de l&#8217;espinagada a\u00a0<strong>sa Pobla<\/strong>\u00a0\u00e9s el bar Can\u00a0<strong>Toni Cotxer<\/strong>. A partir del divendres 12 tendran espinagades, anau-hi a tastar-les. M\u00e9s informaci\u00f3 al\u00a0971 54 00 05.<\/p>\n<p><strong>Tallers per fer espinagades<\/strong><\/p>\n<p>Lloseta:\u00a0Taller d\u2019espinagades a c\u00e0rrec d\u2019en Pep Socies. Ser\u00e0 dia 11 de gener de 2024, a les 18 hores, al centre cultural Sa Mina. Places limitades. Els tiquets estaran a la venda a partir de divendres 29\u00a0de desembre a l\u2019estanc de Lloseta. Preu: 16 euros (inclou sopar). S&#8217;hi ha de dur ganivet, coberts, plat fondo i plat pla, tass\u00f3 i peda\u00e7. M\u00e9s informaci\u00f3 al 655 32 00 25.<\/p>\n<p>Sineu: Taller d&#8217;espinagades amb Pep Socies. Ser\u00e0 el dissabte 13 de gener, a les 10 hores, a Cuina de sa Quintana (Sineu). Preu: 25 euros (inclou formaci\u00f3 i dinar). Cada participant hi ha de dur plats (fondo, pla i per a postres), coberts i tass\u00f3. A m\u00e9s d&#8217;espinagades, els assistents aprendran a fer un plat sorpresa, t\u00edpic de la gastronomia santantoniera. Inscripcions al 644208791<\/p>\n<p>Binissalem: El dissabte 13 de gener el celler Can Fumat ha organitzat un taller d\u2019espinagades. Ser\u00e0 al carrer de sa Coma, 10 de Binissalem. Na Cati Pons i na Maria Antonia Garc\u00eda (Els Fogons de Pla\u00e7a) i Antoni Mart\u00ed (responsable del eller) us hi esperen. L&#8217;activitat ser\u00e0 a les 11.00 per anar a visitar les vinyes. Despr\u00e9s comen\u00e7arem l\u2019activitat al celler Can Fumat. Taller i degustaci\u00f3 d\u2019espinagades i cata de vins. Heu de dur davantal i aprimadora. Us podreu emportar una espinagada per coure (per 4\/6 persones). El preu per persona \u00e9s de 48 \u20ac. Les places s\u00f3n limitades i per ordre d\u2019inscripci\u00f3 a:\u00a0<em>elsfogonsdebunyola\u00a0<\/em>[arrova]\u00a0<em>gmail\u00a0<\/em>[punt]\u00a0<em>com<\/em><\/p>\n<pre>Imatge: Can Murt\u00f3 (Binissalem) i Forn Can Rafel.<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":86859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1046,1475],"tags":[],"coauthors":[2053],"class_list":["post-86871","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat-es-en","category-reportatges-i-novetats-en","post_format-post-format-gallery"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temps d&#039;espinagades a Mallorca - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Temps d&#039;espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temps d&#039;espinagades a Mallorca - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Temps d&#039;espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-11T08:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Temps d&#8217;espinagades a Mallorca\",\"datePublished\":\"2024-01-11T08:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Espinagada-Can-Murto-Binissalem.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca\",\"name\":\"Temps d'espinagades a Mallorca - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Espinagada-Can-Murto-Binissalem.jpg\",\"datePublished\":\"2024-01-11T08:40:00+00:00\",\"description\":\"Temps d'espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/temps-despinagades-a-mallorca#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Espinagada-Can-Murto-Binissalem.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Espinagada-Can-Murto-Binissalem.jpg\",\"width\":1080,\"height\":810},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/en\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temps d'espinagades a Mallorca - Gastron\u00f2micament","description":"Temps d'espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca","og_locale":"en_US","og_type":"article","og_title":"Temps d'espinagades a Mallorca - Gastron\u00f2micament","og_description":"Temps d'espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni","og_url":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca","og_site_name":"Gastron\u00f2micament","article_published_time":"2024-01-11T08:40:00+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Written by":"Redacci\u00f3","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Temps d&#8217;espinagades a Mallorca","datePublished":"2024-01-11T08:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca","url":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca","name":"Temps d'espinagades a Mallorca - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg","datePublished":"2024-01-11T08:40:00+00:00","description":"Temps d'espinagades a Mallorca Actualitat, Reportatges i novetats Hi ha diversos forns, cafeteries i restaurants que ofereixen aquest plat t\u00edpic de les festes de Sant Antoni","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/en\/temps-despinagades-a-mallorca#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/01\/Espinagada-Can-Murto-Binissalem.jpg","width":1080,"height":810},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/en\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/86871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/comments?post=86871"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/posts\/86871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media\/86859"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/media?parent=86871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/categories?post=86871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/tags?post=86871"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/en\/wp-json\/wp\/v2\/coauthors?post=86871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}