{"id":69567,"date":"2017-04-26T13:34:03","date_gmt":"2017-04-26T11:34:03","guid":{"rendered":"https:\/\/gastronomicament.cat\/la-diada-ecologica-de-porreres-sera-dia-30-dabril"},"modified":"2022-04-09T10:38:24","modified_gmt":"2022-04-09T08:38:24","slug":"la-diada-ecologica-de-porreres-sera-dia-30-dabril","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril","title":{"rendered":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#8217;abril"},"content":{"rendered":"<blockquote><p><em>Se celebrar\u00e0 diumenge 30 d&#8217;abril, de 9 a 16 hores, i\u00a0t\u00e9 com a tema central els cereals de varietats locals de Mallorca<\/em><\/p><\/blockquote>\n<p>Diumenge 30 d&#8217;abril, de 9 a 16 hores, Porreres acull l&#8217;onzena edici\u00f3 de la\u00a0<strong>Diada Ecol\u00f2gica.\u00a0<\/strong>Hi trobareu la major exposici\u00f3 i venda de productes amb certificaci\u00f3 ecol\u00f2gica de les Illes Balears.<\/p>\n<p>Durant tota la jornada hi haur\u00e0 activitats i hi trobareu<strong>\u00a0exposici\u00f3 i tast de pans fets amb blats antics<\/strong>, tallers, espai infantil, passacarrers i menjar de tota casta, bo i saludable.\u00a0Altres actes programats s\u00f3n:<\/p>\n<ul>\n<li>30 h: Tallers diversos<\/li>\n<li>30 h: Presentaci\u00f3 del documental Me ecol\u00f2gic de Mallorca, a la sala polivalent<\/li>\n<li>12 h: Actuaci\u00f3 castellera dels Al\u00b7lots de Llevant<\/li>\n<li>13 h: Lliurament del premi Producte Ecol\u00f2gic de l&#8217;Any 2017<\/li>\n<li>30 h: Actuaci\u00f3 dels combos de l&#8217;Escola de M\u00fasica de Porreres.<\/li>\n<\/ul>\n<p>La presentaci\u00f3 de la Diada Ecol\u00f2gica de Porreres ha anat a c\u00e0rrec de\u00a0Manel Domenech (Varietats Locals); Jaume Jaume (president d&#8217;Apaema); Francisca Mora, batlessa de Porreres; Aina Socies de Varietats Locals i Miquel Serra (t\u00e8cnic d&#8217;Apaema).<\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?href=https%3A%2F%2Fwww.facebook.com%2FAjuntamentdePorreres%2Fvideos%2F1892902894321614%2F&amp;show_text=0&amp;width=400\" width=\"400\" height=\"400\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Cal destacar que l&#8217;Associaci\u00f3 d&#8217;Agricultors i Pagesos Ecol\u00f2gics de Mallorca (<strong>APAEMA<\/strong>) organitzadora d&#8217;aquesta fira ecol\u00f2gica a Mallorca, juntament amb la col\u00b7laboraci\u00f3 de l&#8217;<strong>Ajuntament de Porreres<\/strong>, ha preparat tot un seguit d&#8217;actes.<\/p>\n<p><strong>Dijous, 27 abril<\/strong><\/p>\n<p>A les 19 h, al Centre Bit d&#8217;Inca.\u00a0<strong>Xerrada: Una visi\u00f3 ecosistem\u00e0tica sobre la Xylella a c\u00e0rrec de Paco Rodr\u00edguez Le\u00f3n<\/strong>, especialista en sanitat vegetal, metagenoma de plantes i organismes esd\u00e0fics.<\/p>\n<p><strong>Divendres, 28 d&#8217;abril<\/strong><\/p>\n<p>A les 19 h, al Centre Flassaders de Palma.\u00a0<strong>Xerrada: L&#8217;alimentaci\u00f3 que ens emmalalteix, tenim alternatives, a c\u00e0rrec de Javier Guzm\u00e1n<\/strong>, director de VSF Just\u00edcia Aliment\u00e0ria.<\/p>\n<p><strong>Dissabte, 29 d&#8217;abril<\/strong><\/p>\n<p>A les 12 h, al Mercat Ecol\u00f2gic de Palma (Pl. dels Patins). T<strong>ast de pans fets amb blats de varietats locals de Mallorca<\/strong>, a c\u00e0rrec dels forners del mercat i l&#8217;Associaci\u00f3 Varietats Locals<\/p>\n<p>A les 20 h,\u00a0a la sala Polivalent de Porreres.\u00a0<strong>Presentaci\u00f3 de la web\u00a0<a href=\"http:\/\/www.cerealsdemallorca.org\/\">www.cerealsdemallorca.org<\/a>\u00a0i xerrada sobre la Situaci\u00f3 actual dels cereals de varietats locals<\/strong>, a c\u00e0rrec de totes les entitats involucrades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se celebrar\u00e0 diumenge 30 d&#8217;abril, de 9 a 16 hores, i t\u00e9 com a tema central&hellip;<\/p>\n","protected":false},"author":1,"featured_media":39860,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1003],"tags":[],"coauthors":[],"class_list":["post-69567","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat-es","post_format-post-format-gallery"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#039;abril - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#039;abril Actualitat Se celebrar\u00e0 diumenge 30 d&#039;abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#039;abril - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#039;abril Actualitat Se celebrar\u00e0 diumenge 30 d&#039;abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-26T11:34:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-09T08:38:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"955\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#8217;abril\",\"datePublished\":\"2017-04-26T11:34:03+00:00\",\"dateModified\":\"2022-04-09T08:38:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg\",\"articleSection\":[\"Actualitat\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\",\"name\":\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg\",\"datePublished\":\"2017-04-26T11:34:03+00:00\",\"dateModified\":\"2022-04-09T08:38:24+00:00\",\"description\":\"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril Actualitat Se celebrar\u00e0 diumenge 30 d'abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg\",\"width\":955,\"height\":450},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril - Gastron\u00f2micament","description":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril Actualitat Se celebrar\u00e0 diumenge 30 d'abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril","og_locale":"es_ES","og_type":"article","og_title":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril - Gastron\u00f2micament","og_description":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril Actualitat Se celebrar\u00e0 diumenge 30 d'abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca","og_url":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril","og_site_name":"Gastron\u00f2micament","article_published_time":"2017-04-26T11:34:03+00:00","article_modified_time":"2022-04-09T08:38:24+00:00","og_image":[{"width":955,"height":450,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Escrito por":"Redacci\u00f3","Tiempo de lectura":"2 minutos","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d&#8217;abril","datePublished":"2017-04-26T11:34:03+00:00","dateModified":"2022-04-09T08:38:24+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg","articleSection":["Actualitat"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril","url":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril","name":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg","datePublished":"2017-04-26T11:34:03+00:00","dateModified":"2022-04-09T08:38:24+00:00","description":"La Diada Ecol\u00f2gica de Porreres ser\u00e0 dia 30 d'abril Actualitat Se celebrar\u00e0 diumenge 30 d'abril, de 9 a 16 hores, i t\u00e9 com a tema central els cereals de varietats locals de Mallorca","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/la-diada-ecologica-de-porreres-sera-dia-30-dabril#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2017\/04\/Fira-Ecologia-de-Porreres-2017-Mallorca.jpg","width":955,"height":450},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/es\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/69567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/comments?post=69567"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/69567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media\/39860"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media?parent=69567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/categories?post=69567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/tags?post=69567"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/coauthors?post=69567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}