{"id":87324,"date":"2024-02-15T11:11:04","date_gmt":"2024-02-15T10:11:04","guid":{"rendered":"https:\/\/gastronomicament.cat\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands"},"modified":"2024-02-19T12:53:43","modified_gmt":"2024-02-19T11:53:43","slug":"jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","title":{"rendered":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &#038; Camps Prime Brands"},"content":{"rendered":"<p>Jos\u00e9 Hidalgo Camacho s&#8217;incorpora a aquest apassionant repte com a director t\u00e8cnic del grup cellerer compr\u00e8s per les dues Cases del Pened\u00e8s capitanejades per l&#8217;en\u00f2leg Toni Cantos: Juv\u00e9 &amp; Camps, elaboradora d&#8217;espumosos de llargues criances, i Propietat d&#8217;Espiells, de vins tranquils, aix\u00ed com Pagos de Anguix, el m\u00e9s recent dels tres cellers situat a la Ribera del Duero, que compta amb el suport estrat\u00e8gic i vitivin\u00edcola de Jos\u00e9 Manuel P\u00e9rez Ovejas. Al seu torn, coordinar\u00e0 les tasques de viticultura de tots els projectes, liderades per Pep Jim\u00e9nez.<\/p>\n<p>L&#8217;arribada del nou t\u00e8cnic ha entusiasmat l&#8217;equip format per Toni Cantos, Pep Jim\u00e9nez i Jos\u00e9 Manuel P\u00e9rez Ovejas, que han reconegut el seu profund coneixement enol\u00f2gic i la seva visi\u00f3 innovadora. Estan conven\u00e7uts \u2014afirmen\u2014, que la seva incorporaci\u00f3 potenciar\u00e0 encara m\u00e9s el prestigi pel qual treballen des dels seus inicis, assegurant el manteniment dels est\u00e0ndards d&#8217;excel\u00b7l\u00e8ncia que els caracteritza: vinyes ecol\u00f2giques, viticultura de respecte i elaboracions de m\u00e0xima qualitat.<\/p>\n<p>Per part seva, Meritxell Juv\u00e9, CEO i 4a generaci\u00f3 familiar, ha comentat que el nomenament de Jos\u00e9 Hidalgo refor\u00e7a, aportant el seu lideratge i experi\u00e8ncia, la direcci\u00f3 del grup i posa en valor la coordinaci\u00f3 entre els grand\u00edssims equips t\u00e8cnics i de viticultura amb els quals es compta en l&#8217;actualitat. Aquesta decisi\u00f3 \u2014assegura\u2014, marca l&#8217;inici d&#8217;una nova etapa que seguir\u00e0 el cam\u00ed estrat\u00e8gic tra\u00e7at per la fam\u00edlia, reafirmant el comprom\u00eds dels seus cellers amb la qualitat i l&#8217;excel\u00b7l\u00e8ncia en l&#8217;elaboraci\u00f3 de vins.<\/p>\n<p>Jos\u00e9 Hidalgo, enginyer i prestigi\u00f3s en\u00f2leg, compta amb una \u00e0mplia traject\u00f2ria tant nacional com internacional, havent desenvolupat la seva carrera a Napa Valley i adquirit coneixement i experi\u00e8ncia en reconeguts cellers del sector. Avui, amb m\u00e9s de 18 anys d&#8217;experi\u00e8ncia, el rioj\u00e0 promet sumar esfor\u00e7os, liderant al ja cohesionat equip per mantenir la seva reputaci\u00f3 al llarg dels anys i els seus est\u00e0ndards de m\u00e0xima qualitat. Una col\u00b7laboraci\u00f3 que promet que donar\u00e0 de parlar i que, segur, portar\u00e0 nous \u00e8xits.<\/p>\n<p><strong>Sobre J&amp;C Prime Brands<br \/>\n<\/strong>J&amp;C Prime Brands, grup liderat per la fam\u00edlia Juv\u00e9, est\u00e0 integrat per la reputada Distribu\u00efdora Primeras Marcas, la prestigiosa i centen\u00e0ria elaboradora d&#8217;espumosos de llargues criances Juv\u00e9 &amp; Camps, el celler de vins tranquils del Pened\u00e8s, Propietat d&#8217;Espiells, i Pagos de Anguix, el projecte de la Casa a la milla d&#8217;or de la Ribera del Duero. Regit pels principis que comparteixen, l&#8217;excel\u00b7l\u00e8ncia i la sostenibilitat, J&amp;C Prime Brands neix amb l&#8217;objectiu de consolidar el projecte d&#8217;una fam\u00edlia cellerera que persegueix la m\u00e0xima qualitat en tots els processos, de la vinya a la taula.<\/p>\n<p><strong>Sobre Juv\u00e9 &amp; Camps<br \/>\n<\/strong>Juv\u00e9 &amp; Camps compta amb una tradici\u00f3 familiar vit\u00edcola consolidada des del 1796 i un llegat en l&#8217;elaboraci\u00f3 de vins espumosos des del 1921 a la comarca del Pened\u00e8s. Actualment, amb Meritxell Juv\u00e9, quarta generaci\u00f3, al capdavant, la centen\u00e0ria casa continua la seva traject\u00f2ria mantenint les seves arrels i amb una visi\u00f3 innovadora i pionera que marca la seva filosofia de treball. Des de fa m\u00e9s de 15 anys cultiva les seves 271 hect\u00e0rees de vinya en ecol\u00f2gic i practica una viticultura regenerativa, protegint el seu ecosistema i la seva biodiversitat. Tot el treball de verema de la propietat es realitza manualment i, en l&#8217;elaboraci\u00f3 dels espumosos, s&#8217;utilitza \u00fanicament el most flor. Juv\u00e9 &amp; Camps, Elaborador Integral, \u00e9s reconegut per la seva mestria en l&#8217;assemblatge, que dona com a fruit uns vins complexos i equilibrats, capa\u00e7os de millorar amb la llarga guarda a l&#8217;ampolla, elegants i aliens a modes, sempre lligats al territori. El segell intr\u00ednsec de la casa \u00e9s l&#8217;estil brut nature i les llargues criances en ampolla, que van des dels 36 fins a m\u00e9s de 108 mesos, i de monovarietals parcel\u00b7laris al m\u00e0xim exponent de l&#8217;art del cupatge. El seu vi m\u00e9s ic\u00f2nic, Juv\u00e9 &amp; Camps Reserva de la Familia Gran Reserva Brut Nature, ha estat incl\u00f2s en les llistes \u00abTop 100 Wines\u00bb de Wine Spectator i \u00abWines of the Year 2023\u00bb de Decanter, i reconegut com a \u00abMillor Vi Tradicional d&#8217;Espanya 2023\u00bb a la publicaci\u00f3 alemanya del grup Meininger, Weinwirtschaft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La figura d&#8217;Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 &#038;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":87320,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1003,1477],"tags":[],"coauthors":[2053],"class_list":["post-87324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat-es","category-reportatges-i-novetats-es"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &amp; Camps Prime Brands - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &amp; Camps Prime Brands Actualitat, Reportatges i novetats La figura d&#039;Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 &amp; Camps i Propietat d&#039;Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &amp; Camps Prime Brands - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &amp; Camps Prime Brands Actualitat, Reportatges i novetats La figura d&#039;Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 &amp; Camps i Propietat d&#039;Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-15T10:11:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T11:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &#038; Camps Prime Brands\",\"datePublished\":\"2024-02-15T10:11:04+00:00\",\"dateModified\":\"2024-02-19T11:53:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\"},\"wordCount\":739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Foto-Jose-Hidalgo.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\",\"name\":\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Foto-Jose-Hidalgo.jpg\",\"datePublished\":\"2024-02-15T10:11:04+00:00\",\"dateModified\":\"2024-02-19T11:53:43+00:00\",\"description\":\"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands Actualitat, Reportatges i novetats La figura d'Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 & Camps i Propietat d'Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Foto-Jose-Hidalgo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Foto-Jose-Hidalgo.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands - Gastron\u00f2micament","description":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands Actualitat, Reportatges i novetats La figura d'Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 & Camps i Propietat d'Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands - Gastron\u00f2micament","og_description":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands Actualitat, Reportatges i novetats La figura d'Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 & Camps i Propietat d'Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases","og_url":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","og_site_name":"Gastron\u00f2micament","article_published_time":"2024-02-15T10:11:04+00:00","article_modified_time":"2024-02-19T11:53:43+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Escrito por":"Redacci\u00f3","Tiempo de lectura":"4 minutos","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 &#038; Camps Prime Brands","datePublished":"2024-02-15T10:11:04+00:00","dateModified":"2024-02-19T11:53:43+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands"},"wordCount":739,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","url":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands","name":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg","datePublished":"2024-02-15T10:11:04+00:00","dateModified":"2024-02-19T11:53:43+00:00","description":"Jos\u00e9 Hidalgo Camacho, nou director t\u00e8cnic dels tres cellers elaboradors del grup Juv\u00e9 & Camps Prime Brands Actualitat, Reportatges i novetats La figura d'Hidalgo liderar\u00e0 els projectes de la m\u00e0 de Toni Cantos, en\u00f2leg de Juv\u00e9 & Camps i Propietat d'Espiells, aix\u00ed com de Jos\u00e9 Manuel P\u00e9rez Ovejas, assessor estrat\u00e8gic de Pagos de Anguix, a Ribera del Duero, i Pep Jim\u00e9nez, director de viticultura de les tres Cases","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/jose-hidalgo-camacho-nou-director-tecnic-dels-tres-cellers-elaboradors-del-grup-jc-prime-brands#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/02\/Foto-Jose-Hidalgo.jpg","width":1200,"height":800},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/es\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/87324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/comments?post=87324"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/87324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media\/87320"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media?parent=87324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/categories?post=87324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/tags?post=87324"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/coauthors?post=87324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}