{"id":91017,"date":"2024-09-18T10:22:48","date_gmt":"2024-09-18T08:22:48","guid":{"rendered":"https:\/\/gastronomicament.cat\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma"},"modified":"2024-09-18T10:25:46","modified_gmt":"2024-09-18T08:25:46","slug":"tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","status":"publish","type":"post","link":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","title":{"rendered":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma"},"content":{"rendered":"<p>Els amants de les tapes i del teatre podran gaudir a partir d&#8217;aquest mes de setembre d&#8217;una nova edici\u00f3 del Teatre de Barra, organitzat per \u00d2rbita Editorial.<\/p>\n<p>El t\u00edtol d&#8217;aquesta 25a edici\u00f3 \u00e9s\u00a0<strong>D\u00e9j\u00e0 Vu<\/strong>, perqu\u00e8 estrenaran cinc noves obres inspirades en les cinc millors dels darrers anys.<\/p>\n<p>Les representacions\u00a0<strong>es faran els dijous 26 de setembre i 3, 10, 17 i 24 d\u2019octubre de 2024, a les 19:50, 20:30, 21:10 i 21:50 hores<\/strong>.<\/p>\n<p>El dissabte 26 d\u2019octubre, a les 20 hores, se celebrar\u00e0 la\u00a0<strong>gran final\u00a0<\/strong>al teatre municipal Mar i Terra.<\/p>\n<p>La venda anticipada i reserva d\u2019entrades\u00a0es pot fer al Bar Mavi i al correu\u00a0<em>orbitaeditorial\u00a0<\/em>[arrova]\u00a0<em>gmail\u00a0<\/em>[punt]\u00a0<em>com<\/em>. La venda d\u2019entrades per al mateix dia de les funcions, es far\u00e0 a partir de les 18:45h, al Bar Mavi. El preu per funci\u00f3 \u00e9s de 5 euros.<\/p>\n<p>La cita est\u00e0 patrocinada per la cervesera Alhambra i t\u00e9 el suport de l&#8217;Ajuntament de Palma i de l&#8217;empresa de serveis d&#8217;impressi\u00f3 Paperoms.<\/p>\n<p>Les obres i els bars on es representaran s\u00f3n els seg\u00fcents:<\/p>\n<ol>\n<li><em>Cap\u00edtol 2<\/em><br \/>\n<strong>Bar Ca na Mercy<\/strong>.\u00a0<a href=\"https:\/\/www.google.cat\/maps\/place\/Ca+na+Mercy\/@39.5834781,2.6475103,17z\/data=!3m1!4b1!4m6!3m5!1s0x129793d93c1543dd:0xff3d7ec4a4929109!8m2!3d39.583474!4d2.6500852!16s%2Fg%2F11rsq5m1j4?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener nofollow\">Carrer de Ramon Muntaner, 46. Palma<\/a><br \/>\nG\u00e8nere: com\u00e8dia<br \/>\nAutor: Toni Serra<br \/>\nDirectora: Alicia Garau<br \/>\nInt\u00e8rprets: Aina Jagla i Santi CelayaEn aquest nou cap\u00edtol, Carolina, es veur\u00e0 implicada en un misteri\u00f3s cas d&#8217;assassinat que est\u00e0 sent investigat pel seductor detectiu privat Raymond Hammett, qui no perdr\u00e0 l&#8217;oportunitat d&#8217;intentar conquistar a la jove.<br \/>\nPodr\u00e0 la nostra protagonista desempallegar-se de les indagacions de l&#8217;investigador?<br \/>\nPodr\u00e0 Raymond trobar el culpable de tot el que est\u00e0 passant?<br \/>\nPer con\u00e8ixer les respostes no es perdin aquest nou cap\u00edtol de les aventures de Caroline&#8230; Perd\u00f3, de Carolina.<strong>2.<\/strong><em>B\u00fa!<\/em><br \/>\n<strong>Bar Mavi<\/strong>.\u00a0<a href=\"https:\/\/www.google.cat\/maps\/place\/Bar+Mavi\/@39.5789931,2.6481447,17z\/data=!4m11!3m10!1s0x129792f89f3147d5:0x1666b7bb1d462383!5m4!1s2024-11-06!2i4!4m1!1i2!8m2!3d39.5804226!4d2.6521903!16s%2Fg%2F1tfncgnw?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener nofollow\">Carrer del 31 de desembre, 29. Palma<\/a><br \/>\nG\u00e8nere: dram\u00e8dia<br \/>\nAutor i director: Alfonso Morillas<br \/>\nInt\u00e8rprets: Rodo Gener i Laura And\u00fajar<br \/>\nEl per\u00edode entre les 3 i les 4 de la matinada \u00e9s considerat com l&#8217;hora del diable, l&#8217;hora bruixa, on qualsevol cosa sobrenatural pot passar. Casualitat o no, ara s\u00f3n les 3 i busques de la matinada a Palma i na Sara s&#8217;ha encaparrotat en baixar al bar on treballa en Pol per intentar contactar amb l&#8217;esperit d&#8217;un client que va morir al local. Emper\u00f2, els fantasmes que acaben manifestant-se van m\u00e9s enll\u00e0 del m\u00f3n espiritual. O no.<strong><em>3.\u00a0<\/em><\/strong><em>La doneta dels pulmons de cuiro<br \/>\n<\/em><strong>Hotel Ars Magna<\/strong>.\u00a0<a href=\"https:\/\/www.google.cat\/maps\/place\/Ars+Magna+Bleisure+Hotel+****\/@39.5789931,2.6481447,17z\/data=!4m11!3m10!1s0x129793ffe197df5b:0x7e9b27ca3eae21e6!5m4!1s2024-11-06!2i4!4m1!1i2!8m2!3d39.578989!4d2.6507196!16s%2Fg%2F11fhz1b6rk?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener nofollow\">Carrer de Blanquerna, 12.<\/a><br \/>\nG\u00e8nere: tragicom\u00e8dia<br \/>\nAutor i director: Bernat Molina<br \/>\nInt\u00e8rprets: Sofia Mu\u00f1iz i Mariona Hauf<br \/>\nLondres, 1969.<br \/>\nEl cam\u00ed groc s&#8217;ha perdut a la boira. Amb dificultat sentim l&#8217;eco de les sabates de rub\u00eds trepijant les rajoles. Oz ha quedat lluny, fins i tot Kansas. L&#8217;arc de sant Mart\u00ed s&#8217;ha esva\u00eft i nom\u00e9s queda una ombra. Negra, com el vestit de la malvada bruixa de l&#8217;oest.<strong><em>4.\u00a0<\/em><\/strong><em>Blaus, marrons i grisos (reloaded)<br \/>\n<\/em><strong>Restaurant Udon<\/strong>.\u00a0<a href=\"https:\/\/www.google.cat\/maps\/place\/UDON+Palma\/@39.5781785,2.6426075,16z\/data=!3m1!5s0x12979257aeb4a1bf:0x9d27c072bfe18cd8!4m10!1m2!2m1!1sRestaurant+Udon!3m6!1s0x12979257aeb90d87:0x74d9d0b5f97b3228!8m2!3d39.5781786!4d2.6508476!15sCg9SZXN0YXVyYW50IFVkb25aESIPcmVzdGF1cmFudCB1ZG9ukgEQYXNpYW5fcmVzdGF1cmFudJoBJENoZERTVWhOTUc5blMwVkpRMEZuU1VSS2VUUlhVV2RuUlJBQuABAA!16s%2Fg%2F11cm0x6vwk?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener nofollow\">Avinguda del Comte Sallent, 12. Palma<\/a><br \/>\nG\u00e8nere: com\u00e8dia polic\u00edaca<br \/>\nAutor: Salvador Oliva<br \/>\nDirector: Luis Venegas<br \/>\nInt\u00e8rprets: Mar Fiol i Salvador Oliva<br \/>\nA la reuni\u00f3 pr\u00e8via a la jornada laboral de la c\u00fapula policial dels agents de pais\u00e0 tot continua com sempre, carregant i recarregant s\u00edmptomes febrils.<strong><em>5.\u00a0<\/em><\/strong><em>Sense ars\u00e8nic, per favor<br \/>\n<\/em><strong>La Paternal\u00a0<\/strong>(antiga gerreria PRADAS).\u00a0<a href=\"https:\/\/www.google.cat\/maps\/place\/Carrer+del+Rei+San%C3%A7,+21,+Nord,+07004+Palma,+Illes+Balears\/@39.5783654,2.6502522,1076m\/data=!3m2!1e3!4b1!4m6!3m5!1s0x129792566592a59d:0xefd99a5445b27369!8m2!3d39.5783613!4d2.6528271!16s%2Fg%2F11csdtcl_l?entry=ttu&amp;g_ep=EgoyMDI0MDkxMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener nofollow\">Carrer del Rei San\u00e7, 21. Palma<\/a><br \/>\nG\u00e8nere: com\u00e8dia<br \/>\nAutor: Joan Benn\u00e0ssar<br \/>\nDirector: \u00c0lex Tejedor<br \/>\nInt\u00e8rprets: Aina Compte i H\u00e9ctor SeoaneMortimer Brewster torna a Brooklyn, el barri que el va veure cr\u00e9ixer, per rememorar un fet important.<br \/>\nLa sorpresa que es trobar\u00e0 capgirar\u00e0 tot all\u00f2 que, fins ara, li permetia mantenir-se de peus a terra.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Les funcions tendran lloc cada dijous del 26 de setembre al 24 d&#8217;octubre<\/p>\n","protected":false},"author":1,"featured_media":91013,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1003,1477],"tags":[],"coauthors":[2053],"class_list":["post-91017","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-actualitat-es","category-reportatges-i-novetats-es","post_format-post-format-gallery"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament<\/title>\n<meta name=\"description\" content=\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d&#039;octubre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament\" \/>\n<meta property=\"og:description\" content=\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d&#039;octubre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T08:22:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T08:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\"},\"author\":{\"name\":\"Redacci\u00f3\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\"},\"headline\":\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma\",\"datePublished\":\"2024-09-18T08:22:48+00:00\",\"dateModified\":\"2024-09-18T08:25:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Teatre-de-Barra-Palma-2024-scaled.jpg\",\"articleSection\":[\"Actualitat\",\"Reportatges i novetats\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\",\"name\":\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Teatre-de-Barra-Palma-2024-scaled.jpg\",\"datePublished\":\"2024-09-18T08:22:48+00:00\",\"dateModified\":\"2024-09-18T08:25:46+00:00\",\"description\":\"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d'octubre\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Teatre-de-Barra-Palma-2024-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Teatre-de-Barra-Palma-2024-scaled.jpg\",\"width\":2560,\"height\":1431},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/person\\\/a7c85c537a1ed62799a5b8e0f686a37f\",\"name\":\"Redacci\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3\"},\"sameAs\":[\"http:\\\/\\\/gastronomicament.cat\"],\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament","description":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d'octubre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","og_locale":"es_ES","og_type":"article","og_title":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament","og_description":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d'octubre","og_url":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","og_site_name":"Gastron\u00f2micament","article_published_time":"2024-09-18T08:22:48+00:00","article_modified_time":"2024-09-18T08:25:46+00:00","og_image":[{"width":2560,"height":1431,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3","twitter_card":"summary_large_image","twitter_creator":"@gastronomicamen","twitter_site":"@gastronomicamen","twitter_misc":{"Escrito por":"Redacci\u00f3","Tiempo de lectura":"4 minutos","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#article","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma"},"author":{"name":"Redacci\u00f3","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f"},"headline":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma","datePublished":"2024-09-18T08:22:48+00:00","dateModified":"2024-09-18T08:25:46+00:00","mainEntityOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg","articleSection":["Actualitat","Reportatges i novetats"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","url":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma","name":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma - Gastron\u00f2micament","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg","datePublished":"2024-09-18T08:22:48+00:00","dateModified":"2024-09-18T08:25:46+00:00","description":"Tapes i bona dramat\u00fargia a la nova edici\u00f3 del Teatre de Barra de Palma Actualitat, Reportatges i novetats Les funcions tendran lloc cada dijous del 26 de setembre al 24 d'octubre","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/tapes-i-bona-dramaturgia-a-la-nova-edicio-del-teatre-de-barra-de-palma#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2024\/09\/Teatre-de-Barra-Palma-2024-scaled.jpg","width":2560,"height":1431},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]},{"@type":"Person","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/person\/a7c85c537a1ed62799a5b8e0f686a37f","name":"Redacci\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g69fea3cce3645dfa2166e7293e22955e","url":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9489a485c464fd611d33825daae651d13db70c4e74c65c94937a15a9d4c3ee14?s=96&d=mm&r=g","caption":"Redacci\u00f3"},"sameAs":["http:\/\/gastronomicament.cat"],"url":"https:\/\/gastronomicament.cat\/es\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/91017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/comments?post=91017"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/posts\/91017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media\/91013"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media?parent=91017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/categories?post=91017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/tags?post=91017"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/coauthors?post=91017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}