{"id":73585,"date":"2012-11-05T16:43:21","date_gmt":"2012-11-05T16:43:21","guid":{"rendered":"https:\/\/gastronomicament.cat\/recepta\/recepta-copa-de-tardor"},"modified":"2012-11-05T16:43:21","modified_gmt":"2012-11-05T16:43:21","slug":"recepta-copa-de-tardor","status":"publish","type":"recepta","link":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor","title":{"rendered":"Copa de tardor"},"content":{"rendered":"<p><strong>Ingredients<\/strong>:<\/p>\n<p>Per a 4 raccions<\/p>\n<p>&#8211; 250 g de pur\u00e9 de castanyes<br \/>\n&#8211; 300 g de nata l\u00edquida per muntar<br \/>\n&#8211; 60 g de sucre<br \/>\n&#8211; 50 g de xocolata de cobertura<br \/>\n&#8211; 1 merenga seca (opcional)<\/p>\n<p><strong>Preparaci\u00f3<\/strong>:<\/p>\n<p>Escalfau 50 g de nata dins una cassola. En bullir, abocau-la damunt la xocolata trossejada i remenau amb una forqueta fins que estigui completament dissolta. Reservau-la a temperatura ambient.<\/p>\n<p>Muntau la resta de la nata (si hi posau un pessic de sal puja millor). Quan sigui ben ferma, reservau-la a la gelera.<\/p>\n<p>Bateu la crema de castanyes amb el sucre amb una batedora manual de barnilles o amb una forqueta. Quan el sucre estigui ben incorporat, afegiu-hi la nata muntada. Mesclau amb una esp\u00e0tula o amb una cullera de fusta, amb moviments suaus de dalt a baix que permetin l\u2019entrada d\u2019aire, nom\u00e9s fins assegurar-vos que la crema \u00e9s homog\u00e8nia. Posau la preparaci\u00f3 dins una m\u00e0niga de pastisseria, amb la boca d\u2019estrella. Distribu\u00efu la crema dins 4 copes no gaire grans.<\/p>\n<p>Trossejau la merenga amb els dits i repartiu-la per damunt la crema de castanyes. Distribu\u00efu la xocolata per damunt de manera decorativa (si s\u2019ha espessit massa, posau-la un moment al microones perqu\u00e8 s\u2019aclareixi i sigui m\u00e9s f\u00e0cil de manipular).<\/p>\n<p><strong>Nota<\/strong>:<\/p>\n<p>Fer pur\u00e9 de castanyes \u00e9s molt labori\u00f3s, ja que s\u2019han d\u2019obrir amb un ganivet, bullir-les i llavors pelar-les (qu\u00e9 no \u00e9s precisament senzill). Una bona opci\u00f3 \u00e9s comprar el pur\u00e9 ja fet. Nosaltres hem fet el plat amb pur\u00e9 casol\u00e0 una vegada, i una altra amb el que comercialitza la casa Cuevas. La veritat \u00e9s que no hi hem trobat difer\u00e8ncia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredients: Per a 4 raccions &#8211; 250 g de pur\u00e9 de castanyes &#8211; 300 g de nata l\u00edquida per muntar &#8211; 60 g de sucre &#8211; 50 g de xocolata de cobertura &#8211; 1 merenga seca (opcional) Preparaci\u00f3: Escalfau 50 g de nata dins una cassola. En bullir, abocau-la damunt la xocolata trossejada i remenau [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":36205,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[1006],"concurs-mossegades":[],"dificultat":[1498],"ingredient":[],"plat":[1007],"preu-per-racio":[1010],"receptes-tematiques":[],"temps-de-preparacio":[],"coauthors":[],"class_list":["post-73585","recepta","type-recepta","status-publish","format-standard","has-post-thumbnail","hentry","category-receptes-es","dificultat-baixa-es","plat-postres-es","preu_per_racio-entre-2-i-5-euros-es"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recepta: copa de tardor<\/title>\n<meta name=\"description\" content=\"Recepta, copa de tardor, pur\u00e9 de castanyes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recepta: copa de tardor\" \/>\n<meta property=\"og:description\" content=\"Recepta, copa de tardor, pur\u00e9 de castanyes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2012\/11\/recepta-copa-de-tardor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5616\" \/>\n\t<meta property=\"og:image:height\" content=\"3744\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Bojos per la Cuina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor\",\"name\":\"Recepta: copa de tardor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/recepta-copa-de-tardor.jpg\",\"datePublished\":\"2012-11-05T16:43:21+00:00\",\"description\":\"Recepta, copa de tardor, pur\u00e9 de castanyes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/recepta-copa-de-tardor.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/recepta-copa-de-tardor.jpg\",\"width\":5616,\"height\":3744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/recepta\\\/recepta-copa-de-tardor#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Receptes\",\"item\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/receptes\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Copa de tardor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recepta: copa de tardor","description":"Recepta, copa de tardor, pur\u00e9 de castanyes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor","og_locale":"es_ES","og_type":"article","og_title":"Recepta: copa de tardor","og_description":"Recepta, copa de tardor, pur\u00e9 de castanyes","og_url":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor","og_site_name":"Gastron\u00f2micament","og_image":[{"width":5616,"height":3744,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2012\/11\/recepta-copa-de-tardor.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gastronomicamen","twitter_misc":{"Tiempo de lectura":"1 minuto","Written by":"Bojos per la Cuina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor","url":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor","name":"Recepta: copa de tardor","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2012\/11\/recepta-copa-de-tardor.jpg","datePublished":"2012-11-05T16:43:21+00:00","description":"Recepta, copa de tardor, pur\u00e9 de castanyes","breadcrumb":{"@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2012\/11\/recepta-copa-de-tardor.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2012\/11\/recepta-copa-de-tardor.jpg","width":5616,"height":3744},{"@type":"BreadcrumbList","@id":"https:\/\/gastronomicament.cat\/es\/recepta\/recepta-copa-de-tardor#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Receptes","item":"https:\/\/gastronomicament.cat\/es\/receptes"},{"@type":"ListItem","position":2,"name":"Copa de tardor"}]},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/recepta\/73585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/recepta"}],"about":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/types\/recepta"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/comments?post=73585"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/recepta\/73585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media\/36205"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media?parent=73585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/categories?post=73585"},{"taxonomy":"concurs_receptes_mossegades","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/concurs-mossegades?post=73585"},{"taxonomy":"dificultat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/dificultat?post=73585"},{"taxonomy":"ingredient","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/ingredient?post=73585"},{"taxonomy":"plat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/plat?post=73585"},{"taxonomy":"preu_per_racio","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/preu-per-racio?post=73585"},{"taxonomy":"tematica","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/receptes-tematiques?post=73585"},{"taxonomy":"temps_de_preparacio","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/temps-de-preparacio?post=73585"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/coauthors?post=73585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}