{"id":54240,"date":"2015-11-12T22:33:01","date_gmt":"2015-11-12T21:33:01","guid":{"rendered":"https:\/\/gastronomicament.cat\/restaurant\/restaurant-la-despensa-del-baron"},"modified":"2024-10-16T10:50:25","modified_gmt":"2024-10-16T08:50:25","slug":"restaurant-la-despensa-del-baron","status":"publish","type":"restaurant","link":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron","title":{"rendered":"Restaurant La Despensa del Bar\u00f3n"},"content":{"rendered":"<p>L&#8217;Hotel Posada Terra Santa de Palma posa a la disposici\u00f3 dels amants de la cuina selecta el seu restaurant: La Despensa del Bar\u00f3n.<\/p>\n<p>Hi trobareu un ambient recollit i bell amb arcades g\u00f2tiques del segle XV. El xef del restaurant La Despensa del Bar\u00f3n \u00e9s Mat\u00edas N. Provvidenti (1982). Es form\u00e0 com a cuiner a l&#8217;Argentina, la seva terra natal. La seva cuina t\u00e9 una forta influ\u00e8ncia de plats asi\u00e0tics, especialment de zones que ha visitat com Laos, Cambodja, Tail\u00e0ndia, Vietnam i l&#8217;\u00cdndia. Tamb\u00e9 ha incorporat a la seva carta les esferificacions i textures de Ferran Adri\u00e0.<\/p>\n<p>Com a plats, hi hem tastat:<\/p>\n<ul>\n<li>el canel\u00f3 verd amb esferificaci\u00f3 de t\u00f2fona, poma caramelitzada i ametles torrades<\/li>\n<li>la ploma ib\u00e8rica amb mel\u00f3s de figues i ceba<\/li>\n<li>el bacall\u00e0 d&#8217;Alaska amb salsa miso (importat directament del Canad\u00e0)<\/li>\n<li>el gua bao, un panet fet al vapor, molt popular als carrers de Taiwan, farcit de verdures i carn de porc.<\/li>\n<\/ul>\n<p>De postres, cal destacar el sorbet de llimona amb flor el\u00e8ctrica, una experi\u00e8ncia diferent gr\u00e0cies a l&#8217;efecte que fa aquesta flor a la boca.<\/p>\n<p>El restaurant t\u00e9 capacitat per a devers 30 persones.<\/p>\n<p>Com a curiositat, heu de saber que l&#8217;hotel va ser la casa senyorial de la baronia de Bunyol\u00ed, al segle XIII, una casa que es recull en el <em>Llibre del Repartiment<\/em> de la Conquesta de Mallorca. Tamb\u00e9 va ser la casa de la baronia de Boixadors (a partir del sele XIV) i propietat dels marqu\u00e8s de Vivot (al segle XIX). L&#8217;Hotel Posada Terra Santa t\u00e9 com a emblema un c\u00e8rvol, animal que va ser l&#8217;escut de l&#8217;antiga baronia de Boixadors (que procedia de Catalunya). La figura d&#8217;aquest animal encara es conserva a la finestra senyorial de la fa\u00e7ana de l&#8217;hotel.<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hi trobareu un ambient recollit i bell amb arcades g\u00f2tiques del segle XV. El xef del&hellip;<\/p>\n","protected":false},"author":1,"featured_media":38849,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"gallery","meta":{"_acf_changed":false,"_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"direccio":"Carrer del Pes de sa Farina, 8","telefon":"971 21 47 42","web":"","horari":"[:ca]Obert de dimarts a diumenge. Nom\u00e9s vespres [:en] Open from Tuesday to Sunday. Only nights  [:es]Abierto de martes a domingo. Solo cenas [:de]Ge\u00f6ffnet: Dienstags-Sonntag. Nur abends ge\u00f6ffnet","preumitja":"25-35 euros","observacions":"","footnotes":""},"categories":[999],"destacatper":[1111],"especialitat":[1054,1063],"localitat":[1065,1041,1042],"coauthors":[2053],"class_list":["post-54240","restaurant","type-restaurant","status-publish","format-gallery","has-post-thumbnail","hentry","category-restaurants-es","destacatper-romantic-es","especialitat-cuina-creativa-es","especialitat-cuina-selecta-es","localitat-centre-palma-es","localitat-mallorca-es","localitat-palma-es","preu-entre-20-i-30-euros-es","preu-mes-de-30-euros-es"],"acf":{"gallery":null,"home_date":{"home_begin_date":null,"home_end_date":null}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurant La Despensa del Bar\u00f3n<\/title>\n<meta name=\"description\" content=\"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurant La Despensa del Bar\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron\" \/>\n<meta property=\"og:site_name\" content=\"Gastron\u00f2micament\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T08:50:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/11\/la-despensa-del-baron-palma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gastronomicamen\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Redacci\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron\",\"name\":\"Restaurant La Despensa del Bar\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/la-despensa-del-baron-palma.jpg\",\"datePublished\":\"2015-11-12T21:33:01+00:00\",\"dateModified\":\"2024-10-16T08:50:25+00:00\",\"description\":\"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron#primaryimage\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/la-despensa-del-baron-palma.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/la-despensa-del-baron-palma.jpg\",\"width\":1800,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurant\\\/restaurant-la-despensa-del-baron#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Restaurants\",\"item\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/restaurants\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurant La Despensa del Bar\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"name\":\"Gastron\u00f2micament\",\"description\":\"Portal de restaurants, receptes i actualitat gastron\u00f2mica\",\"publisher\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#organization\",\"name\":\"Gastron\u00f2micament\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/gastronomicament.cat\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/header-logo.jpg\",\"width\":277,\"height\":39,\"caption\":\"Gastron\u00f2micament\"},\"image\":{\"@id\":\"https:\\\/\\\/gastronomicament.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gastronomicamen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurant La Despensa del Bar\u00f3n","description":"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron","og_locale":"es_ES","og_type":"article","og_title":"Restaurant La Despensa del Bar\u00f3n","og_description":"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa","og_url":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron","og_site_name":"Gastron\u00f2micament","article_modified_time":"2024-10-16T08:50:25+00:00","og_image":[{"width":1800,"height":1350,"url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/11\/la-despensa-del-baron-palma.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gastronomicamen","twitter_misc":{"Tiempo de lectura":"2 minutos","Written by":"Redacci\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron","url":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron","name":"Restaurant La Despensa del Bar\u00f3n","isPartOf":{"@id":"https:\/\/gastronomicament.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron#primaryimage"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron#primaryimage"},"thumbnailUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/11\/la-despensa-del-baron-palma.jpg","datePublished":"2015-11-12T21:33:01+00:00","dateModified":"2024-10-16T08:50:25+00:00","description":"Restaurant La Despensa del Bar\u00f3n - Hotel Posada Terra Santa","breadcrumb":{"@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron#primaryimage","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/11\/la-despensa-del-baron-palma.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2015\/11\/la-despensa-del-baron-palma.jpg","width":1800,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/gastronomicament.cat\/es\/restaurant\/restaurant-la-despensa-del-baron#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Restaurants","item":"https:\/\/gastronomicament.cat\/es\/restaurants"},{"@type":"ListItem","position":2,"name":"Restaurant La Despensa del Bar\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/gastronomicament.cat\/es\/#website","url":"https:\/\/gastronomicament.cat\/es\/","name":"Gastron\u00f2micament","description":"Portal de restaurants, receptes i actualitat gastron\u00f2mica","publisher":{"@id":"https:\/\/gastronomicament.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gastronomicament.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gastronomicament.cat\/es\/#organization","name":"Gastron\u00f2micament","url":"https:\/\/gastronomicament.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","contentUrl":"https:\/\/gastronomicament.cat\/wp-content\/uploads\/2016\/09\/header-logo.jpg","width":277,"height":39,"caption":"Gastron\u00f2micament"},"image":{"@id":"https:\/\/gastronomicament.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gastronomicamen"]}]}},"_links":{"self":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/restaurant\/54240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/restaurant"}],"about":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/types\/restaurant"}],"author":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/comments?post=54240"}],"version-history":[{"count":0,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/restaurant\/54240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media\/38849"}],"wp:attachment":[{"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/media?parent=54240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/categories?post=54240"},{"taxonomy":"destacatper","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/destacatper?post=54240"},{"taxonomy":"especialitat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/especialitat?post=54240"},{"taxonomy":"localitat","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/localitat?post=54240"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/gastronomicament.cat\/es\/wp-json\/wp\/v2\/coauthors?post=54240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}